{"id":12412,"date":"2024-05-24T18:48:17","date_gmt":"2024-05-24T16:48:17","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/?p=12406"},"modified":"2024-05-24T18:48:17","modified_gmt":"2024-05-24T16:48:17","slug":"obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/","title":{"rendered":"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats"},"content":{"rendered":"<h5>Si la seva empresa duu a terme operacions amb persones o entitats vinculades \u2014per exemple, amb altres societats del mateix grup o amb socis amb una participaci\u00f3 igual o superior al 25%, o b\u00e9 els seus familiars, fins al tercer grau\u2014, les ha de valorar a preus de mercat. No obstant aix\u00f2, en uns certs casos tamb\u00e9 ha d&#8217;informar d&#8217;aquestes operacions a Hisenda o documentar-les.<\/h5>\n<hr \/>\n<p>En el marc de les obligacions fiscals que han de complir les empreses, volem recordar-los la import\u00e0ncia d&#8217;informar correctament a Hisenda sobre les operacions realitzades amb persones o entitats vinculades.<\/p>\n<p>Si l&#8217;any passat la seva empresa va efectuar operacions amb persones o entitats vinculades, recordi en quins casos n&#8217;ha d&#8217;informar a Hisenda i a trav\u00e9s de quines declaracions s&#8217;ha de fer.<\/p>\n<h3><strong>Operacions vinculades<\/strong><\/h3>\n<p>Les operacions vinculades s\u00f3n aquelles que la seva empresa fa amb persones o entitats amb les quals t\u00e9 una relaci\u00f3 especial. Aquest tipus d&#8217;operacions inclou, per exemple, transaccions amb altres societats del mateix grup, amb socis que tenen una participaci\u00f3 igual o superior al 25%, o b\u00e9 amb familiars d&#8217;aquests socis fins al tercer grau.<\/p>\n<p>\u00c9s crucial que aquestes operacions es valorin a preus de mercat per garantir la transpar\u00e8ncia i l&#8217;equitat fiscal. No obstant aix\u00f2, en alguns casos, no nom\u00e9s n&#8217;hi ha prou amb valorar-les adequadament, sin\u00f3 que tamb\u00e9 cal documentar-les i informar Hisenda. A continuaci\u00f3, es detallen les obligacions espec\u00edfiques.<\/p>\n<h3><strong>Obligaci\u00f3 de documentar<\/strong><\/h3>\n<h4><strong><em>Dossier d&#8217;operacions vinculades<\/em><\/strong><\/h4>\n<p><strong>Llindar de 250.000 euros:<\/strong> si la seva empresa ha efectuat operacions amb una mateixa persona o entitat vinculada amb un import total igual o superior als 250.000 euros durant l&#8217;exercici, ha de preparar un dossier detallat. Aquest dossier ha de descriure la naturalesa i la valoraci\u00f3 assignada a aquestes operacions, justificant que aquesta valoraci\u00f3 es correspon amb el que pagarien parts independents en condicions similars.<\/p>\n<p><strong>Excepci\u00f3 per a grups fiscals consolidats:<\/strong> si la seva empresa forma part d&#8217;un grup acollit al r\u00e8gim de consolidaci\u00f3 fiscal, no cal confeccionar aquest dossier per a les operacions fetes amb altres societats del mateix grup fiscal.<\/p>\n<h4><strong>Conservaci\u00f3 i presentaci\u00f3 del dossier<\/strong><\/h4>\n<p>El dossier no cal presentar-lo de manera efectiva, per\u00f2 ha d&#8217;estar disponible per si Hisenda el sol\u00b7licita. Hisenda pot requerir aquest document a partir de la finalitzaci\u00f3 del termini voluntari de presentaci\u00f3 de l&#8217;impost sobre societats (IS). En el cas que l&#8217;exercici social de la seva empresa coincideixi amb l&#8217;any natural, aquesta data \u00e9s el 26 de juliol de cada any.<\/p>\n<p><strong>Formulari d&#8217;operacions vinculades (FOV)<\/strong><\/p>\n<p>Per a empreses de redu\u00efda dimensi\u00f3 (Son aquelles que en el per\u00edode impositiu immediat anterior l&#8217;import net de la xifra de negocis hagu\u00e9s estat inferior a 10 milions d&#8217;euros). existeix la possibilitat de presentar electr\u00f2nicament el Formulari d&#8217;operacions vinculades (FOV), que substitueix el dossier esmentat i cal presentar-lo juntament amb la declaraci\u00f3 de l&#8217;IS de l&#8217;exercici.<\/p>\n<p><strong>Model 232: Declaraci\u00f3 informativa d&#8217;operacions vinculades i d&#8217;operacions amb paradisos fiscals<\/strong><\/p>\n<p>A m\u00e9s de la documentaci\u00f3 requerida, les operacions subjectes a l&#8217;obligaci\u00f3 de documentaci\u00f3 s&#8217;han de declarar a trav\u00e9s del model 232.<\/p>\n<p><strong>Termini de presentaci\u00f3<\/strong><\/p>\n<p>El model 232 cal presentar-lo el mes seg\u00fcent als deu mesos posteriors a la conclusi\u00f3 del per\u00edode impositiu. Per exemple, si l&#8217;exercici social de la seva empresa coincideix amb l&#8217;any natural, la presentaci\u00f3 s&#8217;ha de fer el mes de novembre.<\/p>\n<p><strong>Informaci\u00f3 addicional en el model 232<\/strong><\/p>\n<p>A m\u00e9s de les operacions que superen els 250.000 euros anuals amb la mateixa persona vinculada, el model 232 ha d&#8217;incloure:<\/p>\n<ol>\n<li><strong>Operacions espec\u00edfiques:<\/strong> operacions vinculades que, en conjunt, superin els 100.000 euros, com la venda d&#8217;immobles o participacions i operacions amb intangibles.<\/li>\n<li><strong>Operacions rellevants:<\/strong> operacions vinculades del mateix tipus i m\u00e8tode de valoraci\u00f3 que, en conjunt, excedeixin el 50% del volum de negocis de l&#8217;empresa, sense importar el seu import individual.<\/li>\n<li><strong>Patent box:<\/strong> operacions en les quals s&#8217;hagi aplicat la reducci\u00f3 per patent box (incentiu per cessi\u00f3 de patents), independentment de l&#8217;import.<\/li>\n<li><strong>Paradisos fiscals:<\/strong> operacions fetes amb entitats domiciliades en pa\u00efsos o territoris considerats paradisos fiscals, sense importar l&#8217;import i amb independ\u00e8ncia de la vinculaci\u00f3.<\/li>\n<\/ol>\n<p><strong>Empreses de redu\u00efda dimensi\u00f3<\/strong><\/p>\n<p>Per a les empreses de redu\u00efda dimensi\u00f3, la presentaci\u00f3 del formulari FOV juntament amb la declaraci\u00f3 de l&#8217;IS cobreix l&#8217;obligaci\u00f3 de documentar les operacions vinculades. No obstant aix\u00f2, aquestes empreses tamb\u00e9 han de presentar el model 232 al novembre per a complir amb les obligacions d&#8217;informaci\u00f3 addicional.<\/p>\n<p><em>Complir aquestes obligacions de documentaci\u00f3 i informaci\u00f3 \u00e9s essencial per evitar sancions i assegurar la transpar\u00e8ncia en les relacions fiscals de la seva empresa. Els recomanem revisar detalladament les operacions vinculades fetes durant l&#8217;exercici i assegurar-se que es compleixin els requisits establerts per la normativa vigent.<\/em><\/p>\n<p>Es poden posar en contacte amb aquest despatx professional per qualsevol dubte o aclariment que puguin tenir sobre aquesta q\u00fcesti\u00f3.<\/p>\n<p>Una salutaci\u00f3 cordial,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si la seva empresa duu a terme operacions amb persones o entitats vinculades \u2014per exemple, amb altres societats del mateix grup o amb socis amb una participaci\u00f3 igual o superior al 25%, o b\u00e9 els seus familiars, fins al tercer grau\u2014, les ha de valorar a preus de mercat. No obstant aix\u00f2, en uns certs [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,16],"tags":[],"class_list":["post-12412","post","type-post","status-publish","format-standard","hentry","category-butlleti-mensual","category-destacats","category-fiscal-i-comptable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Si la seva empresa duu a terme operacions amb persones o entitats vinculades \u2014per exemple, amb altres societats del mateix grup o amb socis amb una participaci\u00f3 igual o superior al 25%, o b\u00e9 els seus familiars, fins al tercer grau\u2014, les ha de valorar a preus de mercat. No obstant aix\u00f2, en uns certs [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-24T16:48:17+00:00\" \/>\n<meta name=\"author\" content=\"Administrador Finques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Finques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/\"},\"author\":{\"name\":\"Administrador Finques\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/393d054648944d73a9704339ae3c804c\"},\"headline\":\"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats\",\"datePublished\":\"2024-05-24T16:48:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/\"},\"wordCount\":841,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Fiscal i comptable\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/\",\"name\":\"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"datePublished\":\"2024-05-24T16:48:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/393d054648944d73a9704339ae3c804c\",\"name\":\"Administrador Finques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g\",\"caption\":\"Administrador Finques\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/","og_locale":"en_US","og_type":"article","og_title":"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats | RM Assessors","og_description":"Si la seva empresa duu a terme operacions amb persones o entitats vinculades \u2014per exemple, amb altres societats del mateix grup o amb socis amb una participaci\u00f3 igual o superior al 25%, o b\u00e9 els seus familiars, fins al tercer grau\u2014, les ha de valorar a preus de mercat. No obstant aix\u00f2, en uns certs [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2024-05-24T16:48:17+00:00","author":"Administrador Finques","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"Administrador Finques","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/"},"author":{"name":"Administrador Finques","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/393d054648944d73a9704339ae3c804c"},"headline":"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats","datePublished":"2024-05-24T16:48:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/"},"wordCount":841,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"articleSection":["Butllet\u00ed mensual","Destacats","Fiscal i comptable"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/","url":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/","name":"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"datePublished":"2024-05-24T16:48:17+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/obligacio-de-documentar-operacions-vinculades-en-l-impost-sobre-societats-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Obligaci\u00f3 de documentar operacions vinculades en l\u2019impost sobre societats"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/393d054648944d73a9704339ae3c804c","name":"Administrador Finques","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g","caption":"Administrador Finques"}}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/12412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=12412"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/12412\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=12412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=12412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=12412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}