{"id":12814,"date":"2024-07-18T10:37:24","date_gmt":"2024-07-18T08:37:24","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/?p=12814"},"modified":"2024-07-18T10:37:24","modified_gmt":"2024-07-18T08:37:24","slug":"lagencia-tributaria-vigila-els-moviments-en-metallic","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/","title":{"rendered":"L&#8217;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic"},"content":{"rendered":"<h5>\nL&#8217;\u00fas de m\u00e8todes de pagament electr\u00f2nics, com ara targetes de d\u00e8bit i cr\u00e8dit, tecnologia NFC o aplicacions com Bizum, est\u00e0 en augment. No obstant, els diners en efectiu continuen sent els preferits per molts per pagar en establiments f\u00edsics. Les transaccions en met\u00e0l\u00b7lic s\u00f3n les m\u00e9s vigilades per l&#8217;Ag\u00e8ncia Tribut\u00e0ria, prestant una atenci\u00f3 especial als moviments de grans sumes de bitllets i monedes.<\/h5>\n<p>Segons informa el diari econ\u00f2mic, El Confidencial, del 18 de juliol, el control exhaustiu de l&#8217;Ag\u00e8ncia Tribut\u00e0ria t\u00e9 com a objectiu principal prevenir delictes com el blanqueig de capitals, el frau i altres activitats il\u00b7l\u00edcites relacionades amb els diners en efectiu. Tenir diners a casa no est\u00e0 prohibit. Tot i que guardar els estalvis &#8220;sota el matal\u00e0s&#8221; segueix sent legal, <strong>\u00e9s fonamental con\u00e8ixer certs detalls per evitar problemes amb Hisenda<\/strong>.<\/p>\n<h3>Moviments en efectiu<\/h3>\n<ul>\n<li><span style=\"font-size: 16px;\"><strong>Quantitats superiors a 3.000 euros o amb bitllets de 500 euros<\/strong>: <\/span><span style=\"font-size: 16px;\">Segons l&#8217;article 93 de la Llei General Tribut\u00e0ria, els bancs estan obligats a proporcionar tota la informaci\u00f3 rellevant sobre els seus moviments quan es tracta de quantitats superiors a 3.000 euros o que impliquin bitllets de 500 euros. <\/span><\/li>\n<li><span style=\"font-size: 16px;\"><strong>Fraccionament d&#8217;operacions<\/strong>:\u00a0 Els bancs tamb\u00e9 informen sobre moviments sospitosos que puguin implicar fraccionament d&#8217;operacions per evitar el control fiscal. <\/span><\/li>\n<li><strong><span style=\"font-size: 16px;\">Quantitats superiors a 1.000 euros: <\/span><\/strong><span style=\"font-size: 16px;\">A m\u00e9s, qualsevol operaci\u00f3 en efectiu igual o superior a 1.000 euros pot requerir identificaci\u00f3 addicional per part del banc, especialment si hi ha indicis de blanqueig de capitals.<\/span><\/li>\n<\/ul>\n<h3>Quantitat m\u00e0xima d&#8217;efectiu que es pot tenir<\/h3>\n<ul>\n<li><span style=\"font-size: 16px;\"><strong>100.000 euros:<\/strong> El l\u00edmit que una persona pot moure dins del territori de l&#8217;Estat \u00e9s de 100.000 euros. <\/span><\/li>\n<li><span style=\"font-size: 16px;\"><strong>Grans quantitats:<\/strong> <\/span><span style=\"font-size: 16px;\">A m\u00e9s a m\u00e9s, si les autoritats troben grans sumes de diners durant una inspecci\u00f3, aix\u00f2 pot aixecar sospites i portar a investigacions sobre l&#8217;origen dels fons.<\/span><\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-7747\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/04\/Topall-base-salarial-minima-300x291.jpg\" alt=\"\" width=\"300\" height=\"291\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/04\/Topall-base-salarial-minima-300x291.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/04\/Topall-base-salarial-minima-768x744.jpg 768w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/04\/Topall-base-salarial-minima.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3><span style=\"color: #3366ff;\"><em>Som assessors fiscals. Consulteu-nos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.\u00a0<\/em><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00fas de m\u00e8todes de pagament electr\u00f2nics, com ara targetes de d\u00e8bit i cr\u00e8dit, tecnologia NFC o aplicacions com Bizum, est\u00e0 en augment. No obstant, els diners en efectiu continuen sent els preferits per molts per pagar en establiments f\u00edsics. Les transaccions en met\u00e0l\u00b7lic s\u00f3n les m\u00e9s vigilades per l&#8217;Ag\u00e8ncia Tribut\u00e0ria, prestant una atenci\u00f3 especial als [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"audio","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,16],"tags":[2877,2876,2875],"class_list":["post-12814","post","type-post","status-publish","format-audio","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-fiscal-i-comptable","tag-agencia-tributaria-efectiu","tag-control-bancari-efectiu","tag-limit-diners-efectiu","post_format-post-format-audio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"L&#8217;\u00fas de m\u00e8todes de pagament electr\u00f2nics, com ara targetes de d\u00e8bit i cr\u00e8dit, tecnologia NFC o aplicacions com Bizum, est\u00e0 en augment. No obstant, els diners en efectiu continuen sent els preferits per molts per pagar en establiments f\u00edsics. Les transaccions en met\u00e0l\u00b7lic s\u00f3n les m\u00e9s vigilades per l&#8217;Ag\u00e8ncia Tribut\u00e0ria, prestant una atenci\u00f3 especial als [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-18T08:37:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/02\/Infractor.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Albert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Albert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/\"},\"author\":{\"name\":\"Albert\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\"},\"headline\":\"L&#8217;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic\",\"datePublished\":\"2024-07-18T08:37:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/\"},\"wordCount\":347,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Infractor.jpg\",\"keywords\":[\"Ag\u00e8ncia Tribut\u00e0ria efectiu\",\"control bancari efectiu\",\"l\u00edmit diners efectiu\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Fiscal i comptable\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/\",\"name\":\"L'Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Infractor.jpg\",\"datePublished\":\"2024-07-18T08:37:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Infractor.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Infractor.jpg\",\"width\":640,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/lagencia-tributaria-vigila-els-moviments-en-metallic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\",\"name\":\"Albert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"caption\":\"Albert\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/","og_locale":"en_US","og_type":"article","og_title":"L'Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic | RM Assessors","og_description":"L&#8217;\u00fas de m\u00e8todes de pagament electr\u00f2nics, com ara targetes de d\u00e8bit i cr\u00e8dit, tecnologia NFC o aplicacions com Bizum, est\u00e0 en augment. No obstant, els diners en efectiu continuen sent els preferits per molts per pagar en establiments f\u00edsics. Les transaccions en met\u00e0l\u00b7lic s\u00f3n les m\u00e9s vigilades per l&#8217;Ag\u00e8ncia Tribut\u00e0ria, prestant una atenci\u00f3 especial als [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2024-07-18T08:37:24+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/02\/Infractor.jpg","type":"image\/jpeg"}],"author":"Albert","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"Albert","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/"},"author":{"name":"Albert","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b"},"headline":"L&#8217;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic","datePublished":"2024-07-18T08:37:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/"},"wordCount":347,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/02\/Infractor.jpg","keywords":["Ag\u00e8ncia Tribut\u00e0ria efectiu","control bancari efectiu","l\u00edmit diners efectiu"],"articleSection":["Butllet\u00ed mensual","Destacats","Fiscal i comptable"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/","url":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/","name":"L'Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/02\/Infractor.jpg","datePublished":"2024-07-18T08:37:24+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/02\/Infractor.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/02\/Infractor.jpg","width":640,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/lagencia-tributaria-vigila-els-moviments-en-metallic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Ag\u00e8ncia Tribut\u00e0ria vigila els moviments en met\u00e0l\u00b7lic"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b","name":"Albert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","caption":"Albert"},"sameAs":["https:\/\/www.rm-assessors.cat\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/12814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=12814"}],"version-history":[{"count":2,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/12814\/revisions"}],"predecessor-version":[{"id":12816,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/12814\/revisions\/12816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/7203"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=12814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=12814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=12814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}