{"id":14171,"date":"2025-09-17T18:46:55","date_gmt":"2025-09-17T16:46:55","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/?p=14171"},"modified":"2025-11-18T16:55:57","modified_gmt":"2025-11-18T15:55:57","slug":"si-l-inquili-es-jubila-s-acaba-el-contracte-del-local","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/","title":{"rendered":"Si l&#8217;inquil\u00ed es jubila\u2026 s&#8217;acaba el contracte del local?"},"content":{"rendered":"<h5>La jubilaci\u00f3 activa\/parcial pot no extingir el contracte si hi ha continu\u00eftat real en l&#8217;activitat; \u00e9s un punt casu\u00edstic que conv\u00e9 documentar b\u00e9. La LAU de 1994 va fixar que els contractes antics de local s&#8217;extingeixen per jubilaci\u00f3 o defunci\u00f3 de l&#8217;arrendatari persona f\u00edsica, amb subrogacions limitades.<\/h5>\n<hr \/>\n<p>En els contractes de local &#8220;antics&#8221; (signats abans del 9 de maig de 1985) regia la pr\u00f2rroga for\u00e7osa de la Llei d&#8217;arrendaments urbans (LAU) 1964: l&#8217;inquil\u00ed podia prorrogar pr\u00e0cticament <em>ad infinitum<\/em>. Aix\u00f2 va canviar amb la LAU de 1994, que va imposar un calendari de sortida: si l&#8217;arrendatari \u00e9s persona f\u00edsica, el contracte s&#8217;extingeix per la seva jubilaci\u00f3 o defunci\u00f3, tret que se subrogui el c\u00f2njuge i continu\u00ef la mateixa activitat; si no hi ha c\u00f2njuge, pot entrar un descendent per a completar fins a vint anys des de l&#8217;entrada en vigor de la llei. En persona jur\u00eddica, la llei va fixar terminis taxats que, en molts casos, van culminar l&#8217;1 de gener de 2015.<\/p>\n<h3><strong>I si el contracte \u00e9s posterior al 9 de maig de 1985?<\/strong><\/h3>\n<p>A partir de l&#8217;anomenat &#8220;Decret Boyer&#8221; (RDL 2\/1985), va desapar\u00e8ixer la pr\u00f2rroga for\u00e7osa per als nous contractes: les parts pacten lliurement la durada. Per\u00f2 compte: si despr\u00e9s de 1985 es va pactar expressament sotmetre&#8217;s a pr\u00f2rroga for\u00e7osa (s\u00ed, va haver-hi molts casos), el Tribunal Suprem ha dit que la durada i extinci\u00f3 es regeixen per la disposici\u00f3 transit\u00f2ria 3a de la LAU 1994, igual que els pre-1985. Resultat pr\u00e0ctic: tamb\u00e9 s&#8217;extingeixen per jubilaci\u00f3 de l&#8217;arrendatari persona f\u00edsica (excepte subrogacions previstes).<\/p>\n<h3><strong>Compta la &#8220;jubilaci\u00f3 activa&#8221;, parcial o flexible?<\/strong><\/h3>\n<p>Aqu\u00ed hi ha matisos. La doctrina tradicional del TS va sostenir que la jubilaci\u00f3 de l&#8217;arrendatari extingeix el contracte fins i tot si segueix al capdavant del negoci. No obstant aix\u00f2, resolucions m\u00e9s recents han diferenciat sup\u00f2sits de jubilaci\u00f3 parcial\/activa (compatibilitzant 50% de pensi\u00f3 i continu\u00eftat en l&#8217;activitat), en els quals no s&#8217;extingeix autom\u00e0ticament el contracte per entendre que no hi ha una retirada plena. \u00c9s un punt casu\u00edstic: conv\u00e9 analitzar l&#8217;expedient concret (modalitat de pensi\u00f3, data, continu\u00eftat real en l&#8217;activitat).<\/p>\n<h3><strong>Com acreditem si l&#8217;inquil\u00ed &#8220;est\u00e0 jubilat&#8221; de veritat?<\/strong><\/h3>\n<p>No n&#8217;hi ha prou amb la vida laboral (nom\u00e9s reflecteix altes\/baixes de cotitzaci\u00f3). L&#8217;idoni \u00e9s demanar un certificat de prestacions de l&#8217;INSS (o &#8220;certificat integral de prestacions&#8221;), que acredita si cobra pensi\u00f3 de jubilaci\u00f3 i des de quan.<\/p>\n<h3><strong>Subrogaci\u00f3 del c\u00f2njuge o descendent<\/strong><\/h3>\n<p>Si el c\u00f2njuge no est\u00e0 jubilat i continua la mateixa activitat, pot subrogar-se; i, en defecte d&#8217;aix\u00f2, un descendent podria entrar nom\u00e9s per a completar el m\u00e0xim de vint anys des de 1995 (r\u00e8gim transitori). L&#8217;activitat ha de ser la mateixa, i hi ha l\u00edmits quan ja va haver-hi transmissions pr\u00e8vies.<\/p>\n<ul>\n<li><strong>Atenci\u00f3. <\/strong>Si l&#8217;arrendatari es jubila plenament i no hi ha subrogaci\u00f3 v\u00e0lida, pot donar-se per acabat el contracte i recuperar el local. Si l&#8217;inquil\u00ed no es jubila (simplement compleix l&#8217;edat i continua treballant), el contracte continua. En contractes posteriors a 1985 sense pacte de pr\u00f2rroga for\u00e7osa, regeixen les cl\u00e0usules pactades (i la LAU vigent), no el r\u00e8gim transitori.<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-13012\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/10\/pis-lloguer-300x233.jpg\" alt=\"\" width=\"300\" height=\"233\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/10\/pis-lloguer-300x233.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/10\/pis-lloguer-600x467.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/10\/pis-lloguer.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h5><span style=\"color: #3366ff;\">Es poden posar en contacte amb aquest despatx professional per qualsevol dubte o aclariment que puguin tenir sobre aquesta q\u00fcesti\u00f3, trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.<\/span><\/h5>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La jubilaci\u00f3 activa\/parcial pot no extingir el contracte si hi ha continu\u00eftat real en l&#8217;activitat; \u00e9s un punt casu\u00edstic que conv\u00e9 documentar b\u00e9. La LAU de 1994 va fixar que els contractes antics de local s&#8217;extingeixen per jubilaci\u00f3 o defunci\u00f3 de l&#8217;arrendatari persona f\u00edsica, amb subrogacions limitades. En els contractes de local &#8220;antics&#8221; (signats abans [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":14168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,17],"tags":[3215,3217,3216],"class_list":["post-14171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-juridica","tag-arrendament-local-jubilacio","tag-desnonament-jubilacio-arrendatari","tag-extincio-contracte-arrendament"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Si l&#039;inquil\u00ed es jubila\u2026 s&#039;acaba el contracte del local? | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Si l&#039;inquil\u00ed es jubila\u2026 s&#039;acaba el contracte del local? | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"La jubilaci\u00f3 activa\/parcial pot no extingir el contracte si hi ha continu\u00eftat real en l&#8217;activitat; \u00e9s un punt casu\u00edstic que conv\u00e9 documentar b\u00e9. La LAU de 1994 va fixar que els contractes antics de local s&#8217;extingeixen per jubilaci\u00f3 o defunci\u00f3 de l&#8217;arrendatari persona f\u00edsica, amb subrogacions limitades. En els contractes de local &#8220;antics&#8221; (signats abans [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T16:46:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T15:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/09\/1pexels-photo-19139351-1758094415_1758098549image.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Administrador Finques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Administrador Finques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/\"},\"author\":{\"name\":\"Administrador Finques\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/393d054648944d73a9704339ae3c804c\"},\"headline\":\"Si l&#8217;inquil\u00ed es jubila\u2026 s&#8217;acaba el contracte del local?\",\"datePublished\":\"2025-09-17T16:46:55+00:00\",\"dateModified\":\"2025-11-18T15:55:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/\"},\"wordCount\":601,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1pexels-photo-19139351-1758094415_1758098549image.jpeg\",\"keywords\":[\"arrendament local jubilaci\u00f3\",\"desnonament jubilaci\u00f3 arrendatari\",\"extinci\u00f3 contracte arrendament\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Jur\u00eddica\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/\",\"name\":\"Si l'inquil\u00ed es jubila\u2026 s'acaba el contracte del local? | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1pexels-photo-19139351-1758094415_1758098549image.jpeg\",\"datePublished\":\"2025-09-17T16:46:55+00:00\",\"dateModified\":\"2025-11-18T15:55:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1pexels-photo-19139351-1758094415_1758098549image.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/1pexels-photo-19139351-1758094415_1758098549image.jpeg\",\"width\":810,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Si l&#8217;inquil\u00ed es jubila\u2026 s&#8217;acaba el contracte del local?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/393d054648944d73a9704339ae3c804c\",\"name\":\"Administrador Finques\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g\",\"caption\":\"Administrador Finques\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Si l'inquil\u00ed es jubila\u2026 s'acaba el contracte del local? | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/","og_locale":"en_US","og_type":"article","og_title":"Si l'inquil\u00ed es jubila\u2026 s'acaba el contracte del local? | RM Assessors","og_description":"La jubilaci\u00f3 activa\/parcial pot no extingir el contracte si hi ha continu\u00eftat real en l&#8217;activitat; \u00e9s un punt casu\u00edstic que conv\u00e9 documentar b\u00e9. La LAU de 1994 va fixar que els contractes antics de local s&#8217;extingeixen per jubilaci\u00f3 o defunci\u00f3 de l&#8217;arrendatari persona f\u00edsica, amb subrogacions limitades. En els contractes de local &#8220;antics&#8221; (signats abans [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2025-09-17T16:46:55+00:00","article_modified_time":"2025-11-18T15:55:57+00:00","og_image":[{"width":810,"height":450,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/09\/1pexels-photo-19139351-1758094415_1758098549image.jpeg","type":"image\/jpeg"}],"author":"Administrador Finques","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"Administrador Finques","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/"},"author":{"name":"Administrador Finques","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/393d054648944d73a9704339ae3c804c"},"headline":"Si l&#8217;inquil\u00ed es jubila\u2026 s&#8217;acaba el contracte del local?","datePublished":"2025-09-17T16:46:55+00:00","dateModified":"2025-11-18T15:55:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/"},"wordCount":601,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/09\/1pexels-photo-19139351-1758094415_1758098549image.jpeg","keywords":["arrendament local jubilaci\u00f3","desnonament jubilaci\u00f3 arrendatari","extinci\u00f3 contracte arrendament"],"articleSection":["Butllet\u00ed mensual","Jur\u00eddica"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/","url":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/","name":"Si l'inquil\u00ed es jubila\u2026 s'acaba el contracte del local? | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/09\/1pexels-photo-19139351-1758094415_1758098549image.jpeg","datePublished":"2025-09-17T16:46:55+00:00","dateModified":"2025-11-18T15:55:57+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/09\/1pexels-photo-19139351-1758094415_1758098549image.jpeg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/09\/1pexels-photo-19139351-1758094415_1758098549image.jpeg","width":810,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/si-l-inquili-es-jubila-s-acaba-el-contracte-del-local\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Si l&#8217;inquil\u00ed es jubila\u2026 s&#8217;acaba el contracte del local?"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/393d054648944d73a9704339ae3c804c","name":"Administrador Finques","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d3f1bd6d92e385be2a64414ca046dfd0894742f3427354cf9879c4644ab34739?s=96&d=mm&r=g","caption":"Administrador Finques"}}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/14171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=14171"}],"version-history":[{"count":2,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/14171\/revisions"}],"predecessor-version":[{"id":14339,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/14171\/revisions\/14339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/14168"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=14171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=14171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=14171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}