{"id":14340,"date":"2025-11-19T17:24:53","date_gmt":"2025-11-19T16:24:53","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/?p=14340"},"modified":"2025-11-19T17:24:53","modified_gmt":"2025-11-19T16:24:53","slug":"hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/","title":{"rendered":"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026"},"content":{"rendered":"<h5>A partir de l&#8217;1 de gener l&#8217;Ag\u00e8ncia Tribut\u00e0ria tindr\u00e0 acc\u00e9s ampliat a les dades sobre pagaments realitzats amb targeta o mitjan\u00e7ant Bizum.<\/h5>\n<hr \/>\n<p>Segon informa avui el diari econ\u00f2mic &#8220;Expansi\u00f3n&#8221;, a\u00a0partir del proper mes de gener les entitats financeres hauran de comunicar mensualment totes les operacions realitzades a trav\u00e9s de Bizum, sense importar-ne la quantia. La supressi\u00f3 dels l\u00edmits tamb\u00e9 afectar\u00e0 les operacions amb targeta efectuades o rebudes per empreses i professionals.<\/p>\n<p>Fins ara, perqu\u00e8 Hisenda pogu\u00e9s obtenir tanta informaci\u00f3 era necessari iniciar procediments m\u00e9s restrictius, com ara una comprovaci\u00f3 o una inspecci\u00f3 formal. Des del proper any ja no ser\u00e0 imprescindible, ja que els bancs estaran obligats a enviar informes mensuals autom\u00e0ticament. Per aix\u00f2 es\u00a0 preveu que caldr\u00e0 modificar la normativa per donar suport a aquest augment del control.<\/p>\n<p>Juntament amb la desaparici\u00f3 dels l\u00edmits d&#8217;informaci\u00f3 sobre Bizum i targetes, Hisenda tamb\u00e9 exigir\u00e0 des del gener que les entitats informin dels contribuents que superin els 25.000 euros anuals en pagaments amb targeta.<\/p>\n<p>&nbsp;<\/p>\n<h5><span style=\"color: #3366ff;\"><em>Som assessors fiscals. Consulteu-nos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.<\/em><\/span><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>A partir de l&#8217;1 de gener l&#8217;Ag\u00e8ncia Tribut\u00e0ria tindr\u00e0 acc\u00e9s ampliat a les dades sobre pagaments realitzats amb targeta o mitjan\u00e7ant Bizum. Segon informa avui el diari econ\u00f2mic &#8220;Expansi\u00f3n&#8221;, a\u00a0partir del proper mes de gener les entitats financeres hauran de comunicar mensualment totes les operacions realitzades a trav\u00e9s de Bizum, sense importar-ne la quantia. La [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[15],"tags":[],"class_list":["post-14340","post","type-post","status-publish","format-standard","hentry","category-rm-assessors"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026 | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026 | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"A partir de l&#8217;1 de gener l&#8217;Ag\u00e8ncia Tribut\u00e0ria tindr\u00e0 acc\u00e9s ampliat a les dades sobre pagaments realitzats amb targeta o mitjan\u00e7ant Bizum. Segon informa avui el diari econ\u00f2mic &#8220;Expansi\u00f3n&#8221;, a\u00a0partir del proper mes de gener les entitats financeres hauran de comunicar mensualment totes les operacions realitzades a trav\u00e9s de Bizum, sense importar-ne la quantia. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-19T16:24:53+00:00\" \/>\n<meta name=\"author\" content=\"Albert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Albert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/\"},\"author\":{\"name\":\"Albert\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\"},\"headline\":\"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026\",\"datePublished\":\"2025-11-19T16:24:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/\"},\"wordCount\":211,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"articleSection\":[\"RM-Assessors\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/\",\"name\":\"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026 | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"datePublished\":\"2025-11-19T16:24:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\",\"name\":\"Albert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"caption\":\"Albert\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026 | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/","og_locale":"en_US","og_type":"article","og_title":"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026 | RM Assessors","og_description":"A partir de l&#8217;1 de gener l&#8217;Ag\u00e8ncia Tribut\u00e0ria tindr\u00e0 acc\u00e9s ampliat a les dades sobre pagaments realitzats amb targeta o mitjan\u00e7ant Bizum. Segon informa avui el diari econ\u00f2mic &#8220;Expansi\u00f3n&#8221;, a\u00a0partir del proper mes de gener les entitats financeres hauran de comunicar mensualment totes les operacions realitzades a trav\u00e9s de Bizum, sense importar-ne la quantia. La [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2025-11-19T16:24:53+00:00","author":"Albert","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"Albert","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/"},"author":{"name":"Albert","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b"},"headline":"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026","datePublished":"2025-11-19T16:24:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/"},"wordCount":211,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"articleSection":["RM-Assessors"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/","url":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/","name":"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026 | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"datePublished":"2025-11-19T16:24:53+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/hisenda-disparara-el-control-als-pagaments-per-bizum-i-amb-targeta-a-partir-del-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Hisenda disparar\u00e0 el control als pagaments per Bizum i amb targeta a partir del 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b","name":"Albert","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","caption":"Albert"},"sameAs":["https:\/\/www.rm-assessors.cat\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/14340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=14340"}],"version-history":[{"count":1,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/14340\/revisions"}],"predecessor-version":[{"id":14341,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/14340\/revisions\/14341"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=14340"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=14340"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=14340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}