{"id":4706,"date":"2020-08-06T18:20:32","date_gmt":"2020-08-06T16:20:32","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/"},"modified":"2020-08-06T18:20:32","modified_gmt":"2020-08-06T16:20:32","slug":"noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/","title":{"rendered":"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19"},"content":{"rendered":"<p>Dem\u00e0 entrar\u00e0 en vigor el <a href=\"https:\/\/apigirona.us6.list-manage.com\/track\/click?u=c9fec421edc4397c1b3515da6&amp;id=9efd3268f9&amp;e=1758055e75\" target=\"_blank\" rel=\"noopener\"><em>Decret Llei 30\/2020, de 4 d&#8217;agost<\/em><\/a>, pel qual s&#8217;estableix el r\u00e8gim sancionador\u00a0 per l&#8217;incompliment de les mesures relacionades amb la crisi sanit\u00e0ria provocada per la COVID-19. Destaquem el seg\u00fcent:<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Algunes infraccions molt greus que es podr\u00e0 sancionar amb multa d&#8217;entre 60.001 i 600.000 euros:<\/strong><\/span><\/p>\n<ul>\n<li>Celebraci\u00f3 d\u2019actes o activitats que hagin estat expressament prohibides o suspeses per les autoritats pel risc que suposen.<\/li>\n<li>L&#8217;incompliment reiterat del deure d&#8217;a\u00efllament domiciliari acordat per les autoritats competents per part de persones que hagin donat positiu de COVID-19.<\/li>\n<li>L&#8217;incompliment reiterat dels protocols, plans o instruccions rebudes per les autoritats competents i la reiteraci\u00f3 d&#8217;infraccions greus.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Algunes infraccions greus que es podr\u00e0 sancionar amb multa d&#8217;entre 3.001 i 60.000 euros i, que en funci\u00f3 de la seva especial gravetat tamb\u00e9 es podr\u00e0 sancionar com a molt greus:<\/strong><\/span><\/p>\n<ul>\n<li>L\u2019incompliment dels l\u00edmits d\u2019aforaments als espais tancats o a l\u2019aire lliure.<\/li>\n<li>L&#8217;incompliment dels horaris d\u2019obertura i tancament per a les diferents tipologies d\u2019establiments i activitats.<\/li>\n<li>\u00a0La celebraci\u00f3 i comercialitzaci\u00f3 de reunions, festes o qualsevol altre tipus d&#8217;activitat o acte permanent o espor\u00e0dic, sigui de car\u00e0cter privat o obert al p\u00fablic, en espais p\u00fablics o privats, en el que es produeixin aglomeracions que impedeixin o dificultin l&#8217;adopci\u00f3 de mesures sanit\u00e0ries de prevenci\u00f3 i produeixin un risc o dany greu per a la salut de la poblaci\u00f3.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Algunes infraccions lleus que es podr\u00e0 sancionar amb multa de fins a 3.000 euros<\/strong><\/span>:<\/p>\n<ul>\n<li>L&#8217;incompliment de\u00a0<strong>l\u2019\u00fas de la mascareta o el seu \u00fas inadequat<\/strong>, sancionable amb 100 euros.<\/li>\n<li>L&#8217;incompliment de les\u00a0<strong>mesures d&#8217;higiene i prevenci\u00f3<\/strong>\u00a0establertes per les autoritats competents, per a qualsevol mena d&#8217;establiment o activitat, en espai obert o tancat, p\u00fablic o privat, quan aquest produeixi un risc o dany lleu per a la salut de la poblaci\u00f3.<\/li>\n<li>L&#8217;incompliment de les\u00a0<strong>limitacions de concentraci\u00f3 de persones<\/strong>\u00a0en reunions i o trobades tant en l&#8217;\u00e0mbit privat com el p\u00fablic, en els termes acordats per les autoritats competents, quan aquest produeixi un risc o dany lleu per a la salut de la poblaci\u00f3.<\/li>\n<li>L&#8217;incompliment de la\u00a0<strong>dist\u00e0ncia f\u00edsica interpersonal<\/strong>\u00a0de seguretat, en llocs p\u00fablics o privats, oberts o tancats.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">Compet\u00e8ncia sancionadora<\/span>: <\/strong>Correspon als ajuntaments i a la Generalitat.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Responsabilitat<\/strong><\/span>: Seran responsables les persones f\u00edsiques i jur\u00eddiques que cometin les infraccions, per\u00f2 quan la persona infractora sigui menor d&#8217;edat, en seran responsables subsidiaris els pares, tutors o guardadors legals.<\/p>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4708\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1-300x300.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><em><strong>Som advocats i gestors administratius. Consulte-nos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.<\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dem\u00e0 entrar\u00e0 en vigor el Decret Llei 30\/2020, de 4 d&#8217;agost, pel qual s&#8217;estableix el r\u00e8gim sancionador\u00a0 per l&#8217;incompliment de les mesures relacionades amb la crisi sanit\u00e0ria provocada per la COVID-19. Destaquem el seg\u00fcent: Algunes infraccions molt greus que es podr\u00e0 sancionar amb multa d&#8217;entre 60.001 i 600.000 euros: Celebraci\u00f3 d\u2019actes o activitats que hagin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4708,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,15],"tags":[1673,1674,1675],"class_list":["post-4706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-rm-assessors","tag-infraccions-covid-19","tag-multes-pel-coronavirus","tag-sancions-infraccions-covid-19"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19 | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19 | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Dem\u00e0 entrar\u00e0 en vigor el Decret Llei 30\/2020, de 4 d&#8217;agost, pel qual s&#8217;estableix el r\u00e8gim sancionador\u00a0 per l&#8217;incompliment de les mesures relacionades amb la crisi sanit\u00e0ria provocada per la COVID-19. Destaquem el seg\u00fcent: Algunes infraccions molt greus que es podr\u00e0 sancionar amb multa d&#8217;entre 60.001 i 600.000 euros: Celebraci\u00f3 d\u2019actes o activitats que hagin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-06T16:20:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19\",\"datePublished\":\"2020-08-06T16:20:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/shutterstock_1212954607-1.jpg\",\"keywords\":[\"infraccions Covid-19\",\"multes pel coronavirus\",\"sancions infraccions Covid-19\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/\",\"name\":\"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19 | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/shutterstock_1212954607-1.jpg\",\"datePublished\":\"2020-08-06T16:20:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/shutterstock_1212954607-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/shutterstock_1212954607-1.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19 | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19 | RM Assessors","og_description":"Dem\u00e0 entrar\u00e0 en vigor el Decret Llei 30\/2020, de 4 d&#8217;agost, pel qual s&#8217;estableix el r\u00e8gim sancionador\u00a0 per l&#8217;incompliment de les mesures relacionades amb la crisi sanit\u00e0ria provocada per la COVID-19. Destaquem el seg\u00fcent: Algunes infraccions molt greus que es podr\u00e0 sancionar amb multa d&#8217;entre 60.001 i 600.000 euros: Celebraci\u00f3 d\u2019actes o activitats que hagin [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2020-08-06T16:20:32+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19","datePublished":"2020-08-06T16:20:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg","keywords":["infraccions Covid-19","multes pel coronavirus","sancions infraccions Covid-19"],"articleSection":["Butllet\u00ed mensual","Destacats","RM-Assessors"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/","url":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/","name":"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19 | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg","datePublished":"2020-08-06T16:20:32+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/08\/shutterstock_1212954607-1.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/noves-i-importants-sancions-per-infraccio-de-les-mesures-de-prevencio-de-la-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Noves i importants sancions per infracci\u00f3 de les mesures de prevenci\u00f3 de la Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/4706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=4706"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/4706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/4708"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=4706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=4706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=4706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}