{"id":5051,"date":"2020-11-04T17:36:33","date_gmt":"2020-11-04T15:36:33","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/5051-2\/"},"modified":"2020-11-04T17:36:33","modified_gmt":"2020-11-04T15:36:33","slug":"5051-2","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/","title":{"rendered":"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h."},"content":{"rendered":"<div>El DOGC d\u2019avui publica el\u00a0<em><a href=\"https:\/\/apigirona.us6.list-manage.com\/track\/click?u=c9fec421edc4397c1b3515da6&amp;id=9f78f4b3cc&amp;e=1758055e75\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ff0000;\">Decret llei 39\/2020, de 3 de novembre<\/span><\/a><\/em>, de mesures extraordin\u00e0ries de car\u00e0cter social per fer front a les conseq\u00fc\u00e8ncies de la COVID-19 que permet als treballadors aut\u00f2noms demanar un nou ajut de 2.000 euros. Destaquem el seg\u00fcent:<\/div>\n<div><\/div>\n<div><span style=\"color: #ff0000;\"><strong>Atenci\u00f3. Es molt urgent<\/strong><\/span>: Es tracta d&#8217;un nou ajut de la Generalitat consistent en un pagament \u00fanic de 2.000 euros per cada treballador aut\u00f2nom per\u00f2 limitat a un total de 20 milions d&#8217;euros. L&#8217;Ajut es concedir\u00e0 per ordre de sol\u00b7licitud. Per tant, ser\u00e0 pels 10.000 primers aut\u00f2noms que el demanin i reuneixin les condicions. Aix\u00f2 vol dir que s&#8217;haur\u00e0 d&#8217;anar de pressa.<\/div>\n<div><\/div>\n<div>\n<section>\n<article>\n<article>\n<div><span style=\"color: #ff0000;\"><strong>Qui pot ser beneficiari\/\u00e0ria?:<\/strong><\/span><\/div>\n<ul>\n<li>Treballadors aut\u00f2noms que tinguin fins a 5 persones contractades.<\/li>\n<li>Treballadors aut\u00f2noms que formin part d\u2019una societat, limitada o cooperativa, de fins a 3 socis i que en total siguin un m\u00e0xim de fins a 6 persones (socis + treballadors).<\/li>\n<\/ul>\n<div><span style=\"color: #ff0000;\"><strong>I quins requisits s&#8217;han de complir?<\/strong><\/span><\/div>\n<ul>\n<li>Estar donat d\u2019alta com a aut\u00f2nom com a m\u00ednim abans de l\u20191 de juny i fins el 31 de desembre de 2020.<\/li>\n<li>Que la base imposable de la declaraci\u00f3 de la renda de 2019 sigui igual o inferior a 35.000 euros.<\/li>\n<li>Que segons el model 130 o 131 de l\u2019IRPF, el rendiment net de l\u2019activitat dels tres primers trimestres de l\u2019any 2020 no hagi superat l\u2019import de 13.125 euros.<\/li>\n<\/ul>\n<div><span style=\"color: #ff0000;\"><strong>Quan es pot\u00a0presentar la sol\u00b7licitud? <\/strong><\/span>Est\u00e0\u00a0previst que el termini s&#8217;obri en els propers dies. Concretament, es podran presentar sol\u00b7licituds a partir de les 8 hores del dia seg\u00fcent en que es publiqui la convocat\u00f2ria al DOGC i estar\u00e0 obert durant 10 dies. Les subvencions s\u2019atorgaran per ordre de presentaci\u00f3.<\/div>\n<div><\/div>\n<h3><span style=\"color: #0000ff;\">Atenci\u00f3: Publicada ja la convocat\u00f2ria en el DOG, el termini de presentaci\u00f3 de les sol\u00b7licituds comen\u00e7a el proper dilluns, dia 9 de novembre a les 9 h.<\/span><\/h3>\n<div><\/div>\n<div><strong><span style=\"color: #ff0000;\">Altres informacions d\u2019inter\u00e8s<\/span>:<\/strong><\/div>\n<ul>\n<li>No caldr\u00e0 adjuntar cap document a la sol\u00b7licitud. En tot cas ja els demanar\u00e0 la Generalitat.<\/li>\n<li>Aquest ajut \u00e9s\u00a0compatible\u00a0amb qualsevol altre ajut, prestaci\u00f3, subsidi o subvenci\u00f3, p\u00fablics o privats, destinat a la mateixa finalitat,\u00a0<strong>excepte<\/strong>\u00a0ser beneficiari\/\u00e0ria dels ajuts per afavorir l&#8217;autoocupaci\u00f3 de joves inscrits al programa de\u00a0Garantia Juvenil\u00a0per a l&#8217;any 2020.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4419\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294-300x300.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<\/article>\n<p><span style=\"color: #0000ff;\"><em><strong>Us ho podem tramitar !!!\u00a0 Som gestors administratius. Consulteu-nos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.<\/strong><\/em><\/span><\/p>\n<\/article>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El DOGC d\u2019avui publica el\u00a0Decret llei 39\/2020, de 3 de novembre, de mesures extraordin\u00e0ries de car\u00e0cter social per fer front a les conseq\u00fc\u00e8ncies de la COVID-19 que permet als treballadors aut\u00f2noms demanar un nou ajut de 2.000 euros. Destaquem el seg\u00fcent: Atenci\u00f3. Es molt urgent: Es tracta d&#8217;un nou ajut de la Generalitat consistent en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,15],"tags":[1482,1733,1781],"class_list":["post-5051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-rm-assessors","tag-ajuts-autonoms-catalunya","tag-ajuts-treballadors-autonoms","tag-subvencions-2000-euros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/5051-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"El DOGC d\u2019avui publica el\u00a0Decret llei 39\/2020, de 3 de novembre, de mesures extraordin\u00e0ries de car\u00e0cter social per fer front a les conseq\u00fc\u00e8ncies de la COVID-19 que permet als treballadors aut\u00f2noms demanar un nou ajut de 2.000 euros. Destaquem el seg\u00fcent: Atenci\u00f3. Es molt urgent: Es tracta d&#8217;un nou ajut de la Generalitat consistent en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/5051-2\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-04T15:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h.\",\"datePublished\":\"2020-11-04T15:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/\"},\"wordCount\":438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/shutterstock_1557782294.jpg\",\"keywords\":[\"ajuts aut\u00f2noms Catalunya\",\"ajuts treballadors aut\u00f2noms\",\"subvencions 2000 euros\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/\",\"name\":\"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/shutterstock_1557782294.jpg\",\"datePublished\":\"2020-11-04T15:36:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/shutterstock_1557782294.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/shutterstock_1557782294.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/5051-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/","og_locale":"en_US","og_type":"article","og_title":"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h. | RM Assessors","og_description":"El DOGC d\u2019avui publica el\u00a0Decret llei 39\/2020, de 3 de novembre, de mesures extraordin\u00e0ries de car\u00e0cter social per fer front a les conseq\u00fc\u00e8ncies de la COVID-19 que permet als treballadors aut\u00f2noms demanar un nou ajut de 2.000 euros. Destaquem el seg\u00fcent: Atenci\u00f3. Es molt urgent: Es tracta d&#8217;un nou ajut de la Generalitat consistent en [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2020-11-04T15:36:33+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h.","datePublished":"2020-11-04T15:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/"},"wordCount":438,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg","keywords":["ajuts aut\u00f2noms Catalunya","ajuts treballadors aut\u00f2noms","subvencions 2000 euros"],"articleSection":["Butllet\u00ed mensual","Destacats","RM-Assessors"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/5051-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/","url":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/","name":"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg","datePublished":"2020-11-04T15:36:33+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/5051-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/04\/shutterstock_1557782294.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/5051-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"La Generalitat concedir\u00e0 ajuts de 2.000 euros als 10.000 primers treballadors aut\u00f2noms que els demanin i reuneixin les condicions. Es podran presentar les sol\u00b7licituds a partir del proper dilluns, dia 9 de novembre, a les 9 h."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/5051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=5051"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/5051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/4419"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=5051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=5051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=5051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}