{"id":5903,"date":"2021-06-08T18:33:58","date_gmt":"2021-06-08T16:33:58","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/us-podem-assegurar-els-vostres-viatges\/"},"modified":"2021-06-08T18:33:58","modified_gmt":"2021-06-08T16:33:58","slug":"us-podem-assegurar-els-vostres-viatges","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/","title":{"rendered":"Us podem assegurar els vostres viatges"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><em>Les\u00a0mesures restrictives de mobilitat,\u00a0es van aixecant gradualment i\u00a0segurament ens comen\u00e7arem a plantejar algun viatge, sigui l&#8217;\u00e8poca de l&#8217;any que sigui.\u00a0<strong>Sabeu que podem\u00a0assegurar l&#8217;assist\u00e8ncia en viatge, ja sigui per motius laborals, de lleure o d&#8217;estudi?<\/strong><\/em><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Les assegurances d&#8217;<strong>Assist\u00e8ncia en Viatge<\/strong>\u00a0ens ajudaran a estar tranquils all\u00e0 on ens desplacem, amb unes cobertures \u00fatils i amb unes primes molt contingudes. Els costos de repatriaci\u00f3 i despeses sanit\u00e0ries i hospital\u00e0ries poden ser molt elevades, dep\u00e8n del pa\u00eds a on viatgem, per aquest motiu \u00e9s important concertar aquest tipus d&#8217;assegurances.\u00a0Les garanties b\u00e0siques que cobreixen s\u00f3n:\u00a0<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Garanties b\u00e0siques: <\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><em>Repatriaci\u00f3 o transport sanitari de ferits o malalts.\u00a0<\/em><\/li><li><em> Repatriaci\u00f3 o transport de l&#8217;assegurat difunt.\u00a0<\/em><\/li><li><em>Retorn anticipat per mort d&#8217;un familiar.\u00a0<\/em><\/li><li><em> Despla\u00e7ament d&#8217;un familiar en cas d&#8217;hospitalitzaci\u00f3 o mort de l&#8217;assegurat.\u00a0<\/em><\/li><li><em> Assist\u00e8ncia m\u00e8dica i sanit\u00e0ria.\u00a0<\/em><\/li><li><em> Convalesc\u00e8ncia en hotel.\u00a0 <\/em><\/li><li><em>Retorn anticipat per sinistre greu a casa o local professional.\u00a0<\/em><\/li><li><em> Robatori i danys en l&#8217;equipatge.\u00a0<\/em><\/li><li><em> Recerca i localitzaci\u00f3 d&#8217;equipatge perdut.\u00a0<\/em><\/li><li><em>Enviament de medicaments.\u00a0 <\/em><\/li><li><em>Cobertura de mort i invalidesa\u00a0<\/em><\/li><li><em>Cobertura de Responsabilitat Civil i defensa jur\u00eddica.<\/em>\u00a0<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9 hi ha la possibilitat de contractar altres garanties.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Garanties addicionals: <\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><em> Reintegrament de despeses d&#8217;anul.laci\u00f3 o interrupci\u00f3 del viatge\u00a0, segons condicions especials.<\/em><\/li><li>La<em>\u00a0<strong>COVID<\/strong>\u00a0com a malaltia com\u00fa, incloent despeses m\u00e8diques, farmac\u00e8utiques i d&#8217;hospitalitzaci\u00f3, i si es d\u00f3na positiu, el reemborsament de la PCR\u00a0i les despeses de prolongaci\u00f3 d&#8217;hotel de l&#8217;assegurat i acompanyant.<\/em><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/10\/shutterstock_1477577504-2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/10\/shutterstock_1477577504-2.jpg\" alt=\"\" class=\"wp-image-3769\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/10\/shutterstock_1477577504-2.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/10\/shutterstock_1477577504-2-300x300.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/10\/shutterstock_1477577504-2-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>A RM Assessors us podrem aconsellar i buscar-vos quina \u00e9s la millor opci\u00f3 per tal de que la vostra estada estigui ben coberta. No dubteu en preguntar-nos i us enviarem un pressupost sense cap comprom\u00eds.<\/em><\/strong><\/h5>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les mesures restrictives de mobilitat, es van aixecant gradualment i segurament ens comen\u00e7arem a plantejar algun viatge, sigui l&#8217;\u00e8poca de l&#8217;any que sigui. Sabeu que podem assegurar l&#8217;assist\u00e8ncia en viatge, ja sigui per motius laborals, de lleure o d&#8217;estudi?<\/p>\n","protected":false},"author":1,"featured_media":3562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[18,21,41],"tags":[817,1998,1999],"class_list":["post-5903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assegurances","category-butlleti-mensual","category-destacats","tag-asseguranca-assistencia-viatge","tag-assegurances-rm-assessors","tag-assegurar-el-viatge"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Us podem assegurar els vostres viatges | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Us podem assegurar els vostres viatges | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Les mesures restrictives de mobilitat, es van aixecant gradualment i segurament ens comen\u00e7arem a plantejar algun viatge, sigui l&#039;\u00e8poca de l&#039;any que sigui. Sabeu que podem assegurar l&#039;assist\u00e8ncia en viatge, ja sigui per motius laborals, de lleure o d&#039;estudi?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-08T16:33:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/05\/shutterstock_616299608.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Us podem assegurar els vostres viatges\",\"datePublished\":\"2021-06-08T16:33:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/shutterstock_616299608.jpg\",\"keywords\":[\"asseguran\u00e7a assist\u00e8ncia viatge\",\"assegurances RM assessors\",\"Assegurar el viatge\"],\"articleSection\":[\"Assegurances\",\"Butllet\u00ed mensual\",\"Destacats\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/\",\"name\":\"Us podem assegurar els vostres viatges | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/shutterstock_616299608.jpg\",\"datePublished\":\"2021-06-08T16:33:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/shutterstock_616299608.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/shutterstock_616299608.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/us-podem-assegurar-els-vostres-viatges\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Us podem assegurar els vostres viatges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Us podem assegurar els vostres viatges | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/","og_locale":"en_US","og_type":"article","og_title":"Us podem assegurar els vostres viatges | RM Assessors","og_description":"Les mesures restrictives de mobilitat, es van aixecant gradualment i segurament ens comen\u00e7arem a plantejar algun viatge, sigui l'\u00e8poca de l'any que sigui. Sabeu que podem assegurar l'assist\u00e8ncia en viatge, ja sigui per motius laborals, de lleure o d'estudi?","og_url":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2021-06-08T16:33:58+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/05\/shutterstock_616299608.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Us podem assegurar els vostres viatges","datePublished":"2021-06-08T16:33:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/05\/shutterstock_616299608.jpg","keywords":["asseguran\u00e7a assist\u00e8ncia viatge","assegurances RM assessors","Assegurar el viatge"],"articleSection":["Assegurances","Butllet\u00ed mensual","Destacats"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/","url":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/","name":"Us podem assegurar els vostres viatges | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/05\/shutterstock_616299608.jpg","datePublished":"2021-06-08T16:33:58+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/05\/shutterstock_616299608.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/05\/shutterstock_616299608.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/us-podem-assegurar-els-vostres-viatges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Us podem assegurar els vostres viatges"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/5903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=5903"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/5903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/3562"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=5903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=5903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=5903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}