{"id":5942,"date":"2021-07-17T18:51:02","date_gmt":"2021-07-17T16:51:02","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/en-la-mort-de-jose-maria-gay-de-liebana\/"},"modified":"2021-07-17T18:51:02","modified_gmt":"2021-07-17T16:51:02","slug":"en-la-mort-de-jose-maria-gay-de-liebana","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/","title":{"rendered":"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El passat dia 16 va morir a Barcelona als 68 any el nostre mestre i reputat economista Jos\u00e9 Maria Gay de Li\u00e9bana, que ens va fer l&#8217;honor d&#8217;acompanyar-nos i dissertar en la presentaci\u00f3 de l\u2019agrupaci\u00f3 de les assessories Sanlleh\u00ed i RM Assessors que va tenir lloc  a la Sala Narc\u00eds Monturiol de Figueres el passat 13 de novembre del 2019. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com molt b\u00e9 diu el seu obituari, era un divulgador cient\u00edfic, un gran comunicador i un consumat escriptor. En definitiva, era un economista que enten\u00edem tots. Nosaltres som testimonis que tamb\u00e9 era una gran persona, molt humana i molt propera. El buit que ens ha deixat ser\u00e0 dif\u00edcil d&#8217;omplir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des d&#8217;aquest bloc volem fer arribar el m\u00e9s sentit condol a la seva fam\u00edlia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Descansi en pau. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57-1024x683.jpg\" alt=\"\" class=\"wp-image-3896\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57-1024x683.jpg 1024w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57-300x200.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57-768x513.jpg 768w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57-1536x1025.jpg 1536w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-57-2048x1367.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El passat dia 16 va morir a Barcelona als 68 any el nostre mestre i reputat economista Jos\u00e9 Maria Gay de Li\u00e9bana, que ens va fer l&#8217;honor d&#8217;acompanyar-nos i dissertar en la presentaci\u00f3 de l\u2019agrupaci\u00f3 de les assessories Sanlleh\u00ed i RM Assessors que va tenir lloc  a la Sala Narc\u00eds Monturiol de Figueres el passat 13 de novembre del 2019. <\/p>\n","protected":false},"author":1,"featured_media":3894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[41],"tags":[1382,1367,2017],"class_list":["post-5942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacats","tag-gay-de-liebana","tag-gay-liebana-figueres","tag-sanllehi-rm-assessors"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"El passat dia 16 va morir a Barcelona als 68 any el nostre mestre i reputat economista Jos\u00e9 Maria Gay de Li\u00e9bana, que ens va fer l&#039;honor d&#039;acompanyar-nos i dissertar en la presentaci\u00f3 de l\u2019agrupaci\u00f3 de les assessories Sanlleh\u00ed i RM Assessors que va tenir lloc a la Sala Narc\u00eds Monturiol de Figueres el passat 13 de novembre del 2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-17T16:51:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-49-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana.\",\"datePublished\":\"2021-07-17T16:51:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/\"},\"wordCount\":144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Presentaciofigueres2019-49-scaled.jpg\",\"keywords\":[\"Gay de Li\u00e9bana\",\"Gay Li\u00e9bana Figueres\",\"Sanlleh\u00ed Rm Assessors\"],\"articleSection\":[\"Destacats\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/\",\"name\":\"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Presentaciofigueres2019-49-scaled.jpg\",\"datePublished\":\"2021-07-17T16:51:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Presentaciofigueres2019-49-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/Presentaciofigueres2019-49-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/en-la-mort-de-jose-maria-gay-de-liebana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/","og_locale":"en_US","og_type":"article","og_title":"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana. | RM Assessors","og_description":"El passat dia 16 va morir a Barcelona als 68 any el nostre mestre i reputat economista Jos\u00e9 Maria Gay de Li\u00e9bana, que ens va fer l'honor d'acompanyar-nos i dissertar en la presentaci\u00f3 de l\u2019agrupaci\u00f3 de les assessories Sanlleh\u00ed i RM Assessors que va tenir lloc a la Sala Narc\u00eds Monturiol de Figueres el passat 13 de novembre del 2019.","og_url":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2021-07-17T16:51:02+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-49-scaled.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana.","datePublished":"2021-07-17T16:51:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/"},"wordCount":144,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-49-scaled.jpg","keywords":["Gay de Li\u00e9bana","Gay Li\u00e9bana Figueres","Sanlleh\u00ed Rm Assessors"],"articleSection":["Destacats"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/","url":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/","name":"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-49-scaled.jpg","datePublished":"2021-07-17T16:51:02+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-49-scaled.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/11\/Presentaciofigueres2019-49-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/en-la-mort-de-jose-maria-gay-de-liebana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"En la mort de Jos\u00e9 Maria Gay de Li\u00e9bana."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/5942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=5942"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/5942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/3894"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=5942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=5942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=5942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}