{"id":6262,"date":"2021-12-29T13:15:07","date_gmt":"2021-12-29T11:15:07","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/reforma-laboral-avancem-les-principals-novetats\/"},"modified":"2021-12-29T13:15:07","modified_gmt":"2021-12-29T11:15:07","slug":"reforma-laboral-avancem-les-principals-novetats","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/","title":{"rendered":"Reforma laboral. Avancem les principals novetats"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Les principals novetats de la reforma laboral s\u00f3n la reducci\u00f3 a dos tipus dels contractes temporals, la recuperaci\u00f3 de la ultraactivitat indefinida i la creaci\u00f3 d&#8217;un nou esquema d&#8217;ERTO estructural, anomenat RED.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">El Consell de Ministres va aprovar ahir la reforma laboral que en aquests moments encara est\u00e0 pendent de publicar en el BOE per\u00f2 que est\u00e0 previst que entri en vigor abans de final d&#8217;any. Avancem les principals novetats:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Contractes temporals<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quedaran limitats a dues modalitats:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Estructural<\/li><li>Formatiu<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Contractes temporals estructurals <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En quins casos es podran fer ? <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Quan hi hagi circumst\u00e0ncies de la producci\u00f3 que aix\u00ed ho emparin. Entre elles estaria &#8220;l&#8217;increment ocasional i imprevisible i les oscil\u00b7lacions que, tot i tractant-se d&#8217;activitat normal de l&#8217;empresa, generen un desajust temporal entre l&#8217;ocupaci\u00f3 estable disponible i la que es requereix&#8221;.<\/li><li>Tamb\u00e9 es podran utilitzar per a la cobertura de la vacant d&#8217;un altre treballador, que es pot allargar fins que aquest es reincorpori al lloc de treball.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quina ser\u00e0 la seva durada m\u00e0xima ?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El temps m\u00e0xim de durada per a aquests contractes ser\u00e0 de sis mesos ampliables a 12, sempre que ho permeti el conveni del sector.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es podr\u00e0 encadenar contractes temporals ?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si, per\u00f2 es redueix l&#8217;encadenament dels contractes a l&#8217;hora de considerar un treballador indefinit de 24 a 18 mesos davant dels 24 mesos en un per\u00edode de 30 mesos que actualment estava vigent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Caldr\u00e0 fer alguna cotitzaci\u00f3 addicional ? <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La reforma laboral tamb\u00e9 estableix que els contractes de durada determinada inferior a 30 dies tindran una cotitzaci\u00f3 addicional a c\u00e0rrec de l&#8217;empresari a la finalitzaci\u00f3 del mateix.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Contractes temporals formatius <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Modalitats:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Formaci\u00f3 en alternan\u00e7a<\/li><li>Obtenci\u00f3 de la pr\u00e0ctica professional<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contractes de formaci\u00f3 en alternan\u00e7a:<\/strong> Busca adquirir la compet\u00e8ncia professional adequada corresponent a un nivell d&#8217;estudis determinat (FP, universitat o cat\u00e0leg de qualificacions professionals del Sistema Nacional d&#8217;Ocupaci\u00f3).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/><strong>Contractes per a l&#8217;obtenci\u00f3 de la pr\u00e0ctica professional<\/strong>: Podran fer-se fins a un m\u00e0xim de tres (o cinc anys en el cas de persones amb discapacitat) despr\u00e9s d&#8217;obtinguda la certificaci\u00f3. Tindran entre sis mesos i un any de durada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><br \/>Contractes fix-discontinu<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es potencia el contracte fix-discontinu com la f\u00f3rmula id\u00f2nia per a \u201cla realitzaci\u00f3 de treballs de naturalesa estacional o vinculats a activitats productives de temporada\u201d.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reforma de la subcontractaci\u00f3<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El nou marc regulador determina que sempre hi haur\u00e0 un conveni col\u00b7lectiu sectorial aplicable, que pot ser el de l&#8217;activitat desenvolupada a l&#8217;empresa principal o un altre si aix\u00ed ho determina la negociaci\u00f3 col\u00b7lectiva sectorial dins de les normes generals.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El conveni d&#8217;empresa nom\u00e9s el pot aplicar la contractista si determina millors condicions salarials que el sectorial que sigui aplicable.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Nou model d&#8217;ERTO<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El nou model fixa com a causa estructural i diferenciada dels ERTO per for\u00e7a major les limitacions del desenvolupament habitual de l&#8217;activitat per decisi\u00f3 de l&#8217;autoritat competent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es potencien els ERTO amb exoneracions del 90% per a tots els casos de for\u00e7a major i del 20% per als ERTO anomenats ETOP, els vinculats a causes econ\u00f2miques, t\u00e8cniques, organitzatives i de producci\u00f3, que estaran lligats a la formaci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si les empreses no compleixen el requisit de mantenir l&#8217;ocupaci\u00f3, estaran obligades a tornar totes les exoneracions de cada treballador el contracte del qual s&#8217;hagi extingit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La protecci\u00f3 per desocupaci\u00f3 per al treballador ser\u00e0 del 70% i preveu que no s&#8217;esgotin les prestacions. Per part seva, les companyies obtindran bonificacions addicionals a la Seguretat Social si posen en marxa cursos de formaci\u00f3 per als seus empleats.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ultraactivitat dels convenis<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La nova norma, a difer\u00e8ncia de la reforma del 2012, no estableix un per\u00edode de \u201ccaducitat\u201d una vegada que es denuncia el conveni.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_16.jpg\"><img decoding=\"async\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_16.jpg\" alt=\"\" class=\"wp-image-2198\"\/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><strong><em>Som assessors laborals i de la Seguretat Social. Consulteu-nos sense comprom\u00eds<\/em><\/strong><\/h5>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les novetats principals de la reforma laboral s\u00f3n la reducci\u00f3 a dos tipus dels contractes temporals, la recuperaci\u00f3 de la ultraactivitat indefinida i la creaci\u00f3 d&#8217;un nou esquema d&#8217;ERTO estructural, anomenat RED.<\/p>\n","protected":false},"author":1,"featured_media":800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[41,11],"tags":[2135,2136,2137],"class_list":["post-6262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacats","category-laboral","tag-modificacio-estatut-treballadors","tag-nova-reforma-laboral","tag-reforma-laboral-2022"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reforma laboral. Avancem les principals novetats | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma laboral. Avancem les principals novetats | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Les novetats principals de la reforma laboral s\u00f3n la reducci\u00f3 a dos tipus dels contractes temporals, la recuperaci\u00f3 de la ultraactivitat indefinida i la creaci\u00f3 d&#039;un nou esquema d&#039;ERTO estructural, anomenat RED.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-29T11:15:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral1_20728071.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Reforma laboral. Avancem les principals novetats\",\"datePublished\":\"2021-12-29T11:15:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/\"},\"wordCount\":648,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral1_20728071.jpg\",\"keywords\":[\"modificaci\u00f3 Estatut Treballadors\",\"nova reforma laboral\",\"reforma laboral 2022\"],\"articleSection\":[\"Destacats\",\"Laboral\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/\",\"name\":\"Reforma laboral. Avancem les principals novetats | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral1_20728071.jpg\",\"datePublished\":\"2021-12-29T11:15:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral1_20728071.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral1_20728071.jpg\",\"width\":658,\"height\":325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/reforma-laboral-avancem-les-principals-novetats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reforma laboral. Avancem les principals novetats\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma laboral. Avancem les principals novetats | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/","og_locale":"en_US","og_type":"article","og_title":"Reforma laboral. Avancem les principals novetats | RM Assessors","og_description":"Les novetats principals de la reforma laboral s\u00f3n la reducci\u00f3 a dos tipus dels contractes temporals, la recuperaci\u00f3 de la ultraactivitat indefinida i la creaci\u00f3 d'un nou esquema d'ERTO estructural, anomenat RED.","og_url":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2021-12-29T11:15:07+00:00","og_image":[{"width":658,"height":325,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral1_20728071.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Reforma laboral. Avancem les principals novetats","datePublished":"2021-12-29T11:15:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/"},"wordCount":648,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral1_20728071.jpg","keywords":["modificaci\u00f3 Estatut Treballadors","nova reforma laboral","reforma laboral 2022"],"articleSection":["Destacats","Laboral"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/","url":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/","name":"Reforma laboral. Avancem les principals novetats | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral1_20728071.jpg","datePublished":"2021-12-29T11:15:07+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral1_20728071.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral1_20728071.jpg","width":658,"height":325},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/reforma-laboral-avancem-les-principals-novetats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Reforma laboral. Avancem les principals novetats"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/6262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=6262"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/6262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/800"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=6262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=6262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=6262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}