{"id":6403,"date":"2022-02-16T13:49:49","date_gmt":"2022-02-16T11:49:49","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/"},"modified":"2022-02-16T13:49:49","modified_gmt":"2022-02-16T11:49:49","slug":"liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/","title":{"rendered":"L&#8217;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ?"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Dins del sector de la construcci\u00f3 un dels aspectes que m\u00e9s dubtes genera \u00e9s el tipus impositiu de l&#8217;IVA que s&#8217;ha d&#8217;aplicar a les obres de reforma de pisos en funci\u00f3 del tipus d&#8217;obra realitzada i de les caracter\u00edstiques de l&#8217;habitatge.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Detallen a continuaci\u00f3 quin es el tipus d&#8217;IVA aplicable a cada operaci\u00f3:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tributen al tipus redu\u00eft (10\u2006%) les seg\u00fcents operacions:<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Construcci\u00f3 o rehabilitaci\u00f3 d&#8217;habitatges:<\/strong> <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Execucions d&#8217;obra de&nbsp;construcci\u00f3 o rehabilitaci\u00f3 d&#8217;edificacions destinades sobretot a habitatges, inclosos els locals, garatges i annexos, conseq\u00fc\u00e8ncia de contractes directament formalitzats entre el promotor i el contractista. (No s&#8217;aplica el tipus redu\u00eft a les subcontractes). Es consideren destinades sobretot a habitatges les edificacions en qu\u00e8 almenys el 50\u2006% de la superf\u00edcie constru\u00efda es destini a aquest \u00fas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Ampliaci\u00f3 d&#8217;habitatges:<\/strong> <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Es considera construcci\u00f3, i s&#8217;aplica el 10\u2006%, a l&#8217;ampliaci\u00f3 d&#8217;un habitatge sempre que augmenti la superf\u00edcie habitable. Les obres de reforma interior d&#8217;un habitatge no es consideren construcci\u00f3.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Venda amb instal\u00b7laci\u00f3 d&#8217;armaris per habitatges: <\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Vendes amb instal\u00b7laci\u00f3 d&#8217;armaris de cuina i bany i armaris de paret per a habitatges, conseq\u00fc\u00e8ncia de contractes directament formalitzats entre el promotor de la construcci\u00f3 o rehabilitaci\u00f3 i el contractista.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Construcci\u00f3 de garatges comunitaris:<\/strong> <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Execucions d&#8217;obra directament formalitzades amb&nbsp;comunitats de propietaris&nbsp;per a la&nbsp;construcci\u00f3 de garatges&nbsp;en edificacions destinades sobretot a habitatges, sempre que es realitzin en terrenys comuns i el nombre de places a adjudicar a cada propietari no excedeixi de dues.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Obres de reparaci\u00f3 o renovaci\u00f3 quan el destinatari sigui una persona f\u00edsica&nbsp;i utilitzi l&#8217;habitatge per al seu \u00fas particular<\/strong>. Requisits:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Que la construcci\u00f3 o rehabilitaci\u00f3 hagi finalitzat almenys dos anys abans del comen\u00e7ament de les obres de renovaci\u00f3 o reparaci\u00f3; <\/li><li>Que la persona que executi les obres no aporti\u00a0materials\u00a0per a la seva execuci\u00f3 o, en el cas que els aporti,\u00a0el seu cost no excedeixi del 40 per cent de la base imposable de l&#8217;operaci\u00f3.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Obres de rehabilitaci\u00f3, an\u00e0logues i connexes que tamb\u00e9 tributen al 10%:<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Que es considera obres de rehabilitaci\u00f3 ?<\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>Que m\u00e9s del 50\u2006% del cost total del projecte de rehabilitaci\u00f3 es correspongui amb obres de consolidaci\u00f3 o tractament d&#8217;elements estructurals, fa\u00e7anes o cobertes o amb obres an\u00e0logues o connexes a les de rehabilitaci\u00f3.<\/li><li>Que l&#8217;import total de les obres totals excedeix-hi del 25\u2006% del preu d&#8217;adquisici\u00f3 de l&#8217;edificaci\u00f3 (si es va efectuar en els dos anys anteriors a l&#8217;inici de les obres de rehabilitaci\u00f3), o del valor de mercat de l&#8217;edificaci\u00f3 abans de la seva rehabilitaci\u00f3, descomptant en tots dos casos el valor del s\u00f2l.<\/li><\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Quines son les ob<strong>res an\u00e0logues a les de rehabilitaci\u00f3<\/strong> ?<\/h4>\n\n\n\n<ol class=\"wp-block-list\"><li>Les d&#8217;adequaci\u00f3 estructural que proporcionin a l&#8217;edificaci\u00f3 condicions de seguretat constructiva, de manera que quedi garantida la seva estabilitat i resist\u00e8ncia mec\u00e0nica.<\/li><li>Les de refor\u00e7 o adequaci\u00f3 de la fonamentaci\u00f3, aix\u00ed com les que afectin o consisteixin en el tractament de pilars o forjats.<\/li><li>Les d&#8217;ampliaci\u00f3 de la superf\u00edcie constru\u00efda, sobre i sota rasant.<\/li><li>Les de reconstrucci\u00f3 de fa\u00e7anes i patis interiors.<\/li><li>Les d&#8217;instal\u00b7laci\u00f3 d&#8217;elements elevadors, inclosos els destinats a salvar barreres arquitect\u00f2niques per al seu \u00fas per discapacitats.<\/li><\/ol>\n\n\n\n<h4 class=\"wp-block-heading\">Quines son les o<strong>bres connexes a les de rehabilitaci\u00f3<\/strong> ?<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Es consideraran obres connexes a les de rehabilitaci\u00f3 les que se citen a continuaci\u00f3 quan el seu cost total sigui inferior al derivat de les obres de consolidaci\u00f3 o tractament d&#8217;elements estructurals, fa\u00e7anes o cobertes i, si \u00e9s el cas, de les obres an\u00e0logues a aquestes, sempre que hi estiguin vinculades de manera indissociable i no consisteixin en el mer acabat o adorn de l&#8217;edificaci\u00f3 ni en el simple manteniment o pintura de la fa\u00e7ana:<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Les obres de paleta, lampisteria i fusteria.<\/li><li>Les destinades a la millora i adequaci\u00f3 de tancaments, instal\u00b7lacions el\u00e8ctriques, aigua i climatitzaci\u00f3 i protecci\u00f3 contra incendis.<\/li><li>Les obres de rehabilitaci\u00f3 energ\u00e8tica.<\/li><\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Es consideraran obres de rehabilitaci\u00f3 energ\u00e8tica les destinades a la millora del comportament energ\u00e8tic de les edificacions reduint la seva demanda energ\u00e8tica, a l&#8217;augment del rendiment dels sistemes i instal\u00b7lacions t\u00e8rmiques o a la incorporaci\u00f3 d&#8217;equips que utilitzin fonts d&#8217;energia renovables.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tributen al tipus ordinari del 21% les seg\u00fcents operacions:<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Obres de reparaci\u00f3 o renovaci\u00f3<\/strong>: <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Amb car\u00e0cter general tributen al 21%, per\u00f2 amb les excepcions que hem vist anteriorment pel que fa a certes reparacions o renovacions en habitatges.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Armaris, portes i finestres:<\/strong> <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El lliurament sense instal\u00b7laci\u00f3 de portes, finestres, armaris, mobles de cuina, etc., per a la realitzaci\u00f3 d&#8217;obres en edificacions.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/08\/shutterstock_262830776.jpg\"><img decoding=\"async\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/08\/shutterstock_262830776.jpg\" alt=\"\" class=\"wp-image-2858\"\/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\"><em>Som assessors fiscals. Consulteu-nos sense comprom\u00eds <\/em><\/h5>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dins del sector de la construcci\u00f3 un dels aspectes que m\u00e9s dubtes genera \u00e9s el tipus impositiu de l&#8217;IVA que s&#8217;ha d&#8217;aplicar a les obres de reforma de pisos en funci\u00f3 del tipus d&#8217;obra realitzada i de les caracter\u00edstiques de l&#8217;habitatge.<\/p>\n","protected":false},"author":1,"featured_media":3312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,15],"tags":[2172,2173,2174],"class_list":["post-6403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-rm-assessors","tag-iva-construccio","tag-iva-reduit-obres","tag-iva-reparacions-immobles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ? | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ? | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Dins del sector de la construcci\u00f3 un dels aspectes que m\u00e9s dubtes genera \u00e9s el tipus impositiu de l&#039;IVA que s&#039;ha d&#039;aplicar a les obres de reforma de pisos en funci\u00f3 del tipus d&#039;obra realitzada i de les caracter\u00edstiques de l&#039;habitatge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-16T11:49:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"L&#8217;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ?\",\"datePublished\":\"2022-02-16T11:49:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/\"},\"wordCount\":816,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_3.jpg\",\"keywords\":[\"Iva construcci\u00f3\",\"IVA redu\u00eft obres\",\"IVA reparacions immobles\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/\",\"name\":\"L'IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ? | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_3.jpg\",\"datePublished\":\"2022-02-16T11:49:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_3.jpg\",\"width\":900,\"height\":600,\"caption\":\"To open a window with a mosquito net. Plastic Windows with sunlight background.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ? | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/","og_locale":"en_US","og_type":"article","og_title":"L'IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ? | RM Assessors","og_description":"Dins del sector de la construcci\u00f3 un dels aspectes que m\u00e9s dubtes genera \u00e9s el tipus impositiu de l'IVA que s'ha d'aplicar a les obres de reforma de pisos en funci\u00f3 del tipus d'obra realitzada i de les caracter\u00edstiques de l'habitatge.","og_url":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2022-02-16T11:49:49+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_3.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"L&#8217;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ?","datePublished":"2022-02-16T11:49:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/"},"wordCount":816,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_3.jpg","keywords":["Iva construcci\u00f3","IVA redu\u00eft obres","IVA reparacions immobles"],"articleSection":["Butllet\u00ed mensual","Destacats","RM-Assessors"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/","url":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/","name":"L'IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ? | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_3.jpg","datePublished":"2022-02-16T11:49:49+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_3.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_3.jpg","width":900,"height":600,"caption":"To open a window with a mosquito net. Plastic Windows with sunlight background."},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/liva-en-les-obres-i-reparacions-dimmobles-quan-tributen-al-10-o-al-21\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"L&#8217;IVA en les obres i reparacions d\u2019immobles. Quan tributen al 10% o al 21% ?"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/6403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=6403"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/6403\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/3312"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=6403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=6403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=6403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}