{"id":6966,"date":"2022-12-16T12:00:02","date_gmt":"2022-12-16T10:00:02","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/subvencions-per-al-comerc-al-detall\/"},"modified":"2022-12-16T12:00:02","modified_gmt":"2022-12-16T10:00:02","slug":"subvencions-per-al-comerc-al-detall","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/","title":{"rendered":"Subvencions per al comer\u00e7 al detall"},"content":{"rendered":"<h5>S&#8217;obre la convocat\u00f2ria per a la concessi\u00f3 de subvencions en l&#8217;\u00e0mbit de les activitats de comer\u00e7 al detall, i de les associacions i entitats de comer\u00e7, emmarcat en el programa de modernitzaci\u00f3 del Comer\u00e7: Fons Tecnol\u00f2gic del Pla de Recuperaci\u00f3, Transformaci\u00f3 i Resili\u00e8ncia &#8211; Finan\u00e7at pels fons Next Generation EU. El termini de presentaci\u00f3 de les sol\u00b7licituds, juntament amb la documentaci\u00f3 i annexos comen\u00e7a a les <strong>9:00 hores del dia 15 de desembre de 2022 i acaba a les 14:00 hores del dia 19 de gener de 2023.<\/strong><\/h5>\n<p>En el Diari Oficial de la Generalitat de Catalunya (DOCG) n\u00famero 8809, de 9 de desembre de 2022, s&#8217;ha publicat, la <strong><em><a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8809\/1940867.pdf\" data-cke-saved-href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8809\/1940867.pdf\">RESOLUCI\u00d3<\/a>\u00a0<\/em>per la qual s&#8217;obre la convocat\u00f2ria per a la concessi\u00f3 de subvencions en l&#8217;\u00e0mbit de les activitats de comer\u00e7 al detall. <\/strong>Anteriorment, el 29 de novembre de 2022, es va publicar al DOGC la <strong><em><a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8803\/1939023.pdf\" data-cke-saved-href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8803\/1939023.pdf\">RESOLUCI\u00d3<\/a><\/em> per la qual es dona publicitat a les bases reguladores d\u2019aquestes subvencions.\u00a0<\/strong><\/p>\n<p>Destaquem el seg\u00fcent:<\/p>\n<h3><strong>Objecte de la convocat\u00f2ria:<\/strong><\/h3>\n<ul>\n<li>Ajuts de fins al 80% de les despeses subvencionables amb un m\u00e0xim de 75.000 euros destinats a la modernitzaci\u00f3 del comer\u00e7.<\/li>\n<li>Poden demanar els ajuts els titulats de comer\u00e7os al detall que compleixin els requisits de la base tercera de la convocat\u00f2ria, les entitats territorials, gremis i entitats sectorials de comer\u00e7 sense \u00e0nim de lucre i les associacions de mercats municipals sedentaris i no sedentaris.<\/li>\n<\/ul>\n<h3><strong>Presentaci\u00f3 de la sol\u00b7licituds:\u00a0<\/strong><\/h3>\n<p>El termini comen\u00e7a a les 9:00 hores del dia 15 de desembre de 2022 i acaba a les 14:00 hores del dia 19 de gener de 2023.<\/p>\n<p>Les sol\u00b7licituds s&#8217;han de presentar segons el model normalitzat que est\u00e0 a disposici\u00f3 de les persones interessades a la seu corporativa de <a href=\"https:\/\/canalempresa.gencat.cat\/ca\/01_que_voleu_fer\/mesuresempresesiautonoms\/\" data-cke-saved-href=\"https:\/\/canalempresa.gencat.cat\/ca\/01_que_voleu_fer\/mesuresempresesiautonoms\/\">Canal Empresa de la Generalitat de Catalunya<\/a>,<\/p>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors9_50249475.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-685\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors9_50249475.jpg\" alt=\"\" width=\"658\" height=\"325\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors9_50249475.jpg 658w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors9_50249475-300x148.jpg 300w\" sizes=\"(max-width: 658px) 100vw, 658px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><span style=\"color: #0000ff;\"><em>Som Gestors Administratius. Consulteu-mos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat<\/em><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>S&#8217;obre la convocat\u00f2ria per a la concessi\u00f3 de subvencions en l&#8217;\u00e0mbit de les activitats de comer\u00e7 al detall, i de les associacions i entitats de comer\u00e7, emmarcat en el programa de modernitzaci\u00f3 del Comer\u00e7: Fons Tecnol\u00f2gic del Pla de Recuperaci\u00f3, Transformaci\u00f3 i Resili\u00e8ncia &#8211; Finan\u00e7at pels fons Next Generation EU. El termini de presentaci\u00f3 de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1470,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,15],"tags":[2387,2388,2389],"class_list":["post-6966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-rm-assessors","tag-ajuts-comerc-detall","tag-subvencins-next-generation","tag-subvencions-comerc-detall"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subvencions per al comer\u00e7 al detall | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subvencions per al comer\u00e7 al detall | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"S&#8217;obre la convocat\u00f2ria per a la concessi\u00f3 de subvencions en l&#8217;\u00e0mbit de les activitats de comer\u00e7 al detall, i de les associacions i entitats de comer\u00e7, emmarcat en el programa de modernitzaci\u00f3 del Comer\u00e7: Fons Tecnol\u00f2gic del Pla de Recuperaci\u00f3, Transformaci\u00f3 i Resili\u00e8ncia &#8211; Finan\u00e7at pels fons Next Generation EU. El termini de presentaci\u00f3 de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-16T10:00:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2016\/04\/04-Resolucion-de-Escritorio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Subvencions per al comer\u00e7 al detall\",\"datePublished\":\"2022-12-16T10:00:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/\"},\"wordCount\":320,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/04-Resolucion-de-Escritorio.jpg\",\"keywords\":[\"ajuts comer\u00e7 detall\",\"subvencins Next Generation\",\"subvencions comer\u00e7 detall\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/\",\"name\":\"Subvencions per al comer\u00e7 al detall | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/04-Resolucion-de-Escritorio.jpg\",\"datePublished\":\"2022-12-16T10:00:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/04-Resolucion-de-Escritorio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/04-Resolucion-de-Escritorio.jpg\",\"width\":1619,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/subvencions-per-al-comerc-al-detall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subvencions per al comer\u00e7 al detall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subvencions per al comer\u00e7 al detall | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/","og_locale":"en_US","og_type":"article","og_title":"Subvencions per al comer\u00e7 al detall | RM Assessors","og_description":"S&#8217;obre la convocat\u00f2ria per a la concessi\u00f3 de subvencions en l&#8217;\u00e0mbit de les activitats de comer\u00e7 al detall, i de les associacions i entitats de comer\u00e7, emmarcat en el programa de modernitzaci\u00f3 del Comer\u00e7: Fons Tecnol\u00f2gic del Pla de Recuperaci\u00f3, Transformaci\u00f3 i Resili\u00e8ncia &#8211; Finan\u00e7at pels fons Next Generation EU. El termini de presentaci\u00f3 de [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2022-12-16T10:00:02+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2016\/04\/04-Resolucion-de-Escritorio.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Subvencions per al comer\u00e7 al detall","datePublished":"2022-12-16T10:00:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/"},"wordCount":320,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2016\/04\/04-Resolucion-de-Escritorio.jpg","keywords":["ajuts comer\u00e7 detall","subvencins Next Generation","subvencions comer\u00e7 detall"],"articleSection":["Butllet\u00ed mensual","Destacats","RM-Assessors"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/","url":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/","name":"Subvencions per al comer\u00e7 al detall | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2016\/04\/04-Resolucion-de-Escritorio.jpg","datePublished":"2022-12-16T10:00:02+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2016\/04\/04-Resolucion-de-Escritorio.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2016\/04\/04-Resolucion-de-Escritorio.jpg","width":1619,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/subvencions-per-al-comerc-al-detall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Subvencions per al comer\u00e7 al detall"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/6966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=6966"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/6966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/1470"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=6966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=6966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=6966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}