{"id":7223,"date":"2023-03-13T12:03:43","date_gmt":"2023-03-13T10:03:43","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/on-posara-el-focus-hisenda-en-el-2023\/"},"modified":"2023-03-13T12:03:43","modified_gmt":"2023-03-13T10:03:43","slug":"on-posara-el-focus-hisenda-en-el-2023","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/","title":{"rendered":"On posar\u00e0 el focus Hisenda en el 2023?"},"content":{"rendered":"<h5>Entre les principals l\u00ednies d&#8217;actuaci\u00f3 del Pla Anual de Control Tributari i Duaner de 2023, Hisenda posar\u00e0 el focus a detectar l\u2019economia submergida, especialment en el sector de la rehabilitaci\u00f3 i les reformes d&#8217;immobles, aix\u00ed com per a la identificaci\u00f3 de programari d&#8217;ocultaci\u00f3 de vendes, i es refor\u00e7ar\u00e0 el control sobre cobraments virtuals a trav\u00e9s d&#8217;entitats o aplicacions radicades a l&#8217;estranger, les falses resid\u00e8ncies, aix\u00ed com la recerca sobre criptomonedes, entre altres.<\/h5>\n<hr \/>\n<p>En el BOE del dia 27 de febrer de 2023 s&#8217;ha publicat la <em><a href=\"https:\/\/www.boe.es\/boe\/dias\/2023\/02\/27\/pdfs\/BOE-A-2023-5080.pdf\">Resoluci\u00f3 de 6 de febrer de 2023<\/a><\/em>, de la Direcci\u00f3 General de l&#8217;Ag\u00e8ncia Estatal d&#8217;Administraci\u00f3 Tribut\u00e0ria, per la qual s&#8217;aproven les directrius generals del Pla Anual de Control Tributari i Duaner de 2023.<\/p>\n<p>A continuaci\u00f3 exposarem un breu resum de les principals mesures i actuacions que s&#8217;escometran en aquest exercici 2023 per part d&#8217;Ag\u00e8ncia Estatal d&#8217;Administraci\u00f3 Tribut\u00e0ria (AEAT):<\/p>\n<ul>\n<li><strong>Imposici\u00f3 de sancions tribut\u00e0ries: <\/strong>S&#8217;establir\u00e0 un nou criteri que ser\u00e0 rellevant per a la seva imposici\u00f3: l&#8217;historial de compliment i incompliment del contribuent.<\/li>\n<li><strong>Devolucions<\/strong>: Es procur\u00e0 avan\u00e7ar les devolucions de les declaracions de l&#8217;impost sobre societats a petites i mitjanes empreses.<\/li>\n<li><strong>Contribuents amb alta capacitat econ\u00f2mica<\/strong>:Es continuar\u00e0 amb les labors de recerca directa sobre contribuents d&#8217;alta capacitat econ\u00f2mica per a la detecci\u00f3 i regularitzaci\u00f3 dels comportaments irregulars en qu\u00e8 incorrin.<\/li>\n<li><strong>Informaci\u00f3 sobre immobles<\/strong>: Es treballar\u00e0 en la utilitzaci\u00f3 massiva de la nova informaci\u00f3 sobre immobles i societats procedent del Consell General del Notariat (\u00cdndex \u00danic Notarial).<\/li>\n<li><strong>Economia submergida<\/strong>:Es mantindr\u00e0 el control d&#8217;\u00a0aquells sectors i models de negoci en els quals s&#8217;apreci\u00ef un alt risc d&#8217;exist\u00e8ncia d&#8217;economia submergida, amb especial atenci\u00f3 a l&#8217;\u00fas intensiu d&#8217;efectiu o a l&#8217;\u00fas de m\u00e8todes electr\u00f2nics de pagament radicats a l&#8217;estranger i no subjectes, de fet, o de dret, a les obligacions de subministrament d&#8217;informaci\u00f3.<\/li>\n<li><strong>Control sobre les despeses personals imputades a les societats<\/strong>: Es programaran actuacions dirigides a evitar l&#8217;\u00fas abusiu de la personalitat jur\u00eddica amb la principal finalitat de canalitzar rendes, o desviar indegudament despeses personals de persones f\u00edsiques, de manera que es redueixin improcedentment els tipus impositius aplicables.<\/li>\n<li><strong>Factures falses<\/strong>: Es seguir\u00e0 amb la comprovaci\u00f3 d&#8217;aquelles entitats que han estat creades instrumentalment amb l&#8217;\u00fanica fi d&#8217;emetre factures irregulars per a ser dedu\u00efdes per societats operatives.<\/li>\n<li><strong>Comunitats de bens:<\/strong> Es comprovar\u00e0 la correcta imputaci\u00f3 de rendes als seus socis per part de comunitats de b\u00e9ns o altres entitats en r\u00e8gim d&#8217;atribuci\u00f3 de rendes que desenvolupin activitats econ\u00f2miques, aix\u00ed com la realitat dels rendiments declarats per aquestes.<\/li>\n<li><strong>Bens de luxe<\/strong>: Es controlar\u00e0 la falsa afectaci\u00f3 a l&#8217;activitat econ\u00f2mica de b\u00e9ns de luxe o de serveis relacionats amb el sector del luxe per part de persones jur\u00eddiques l&#8217;activitat de les quals no es trobi vinculada amb l&#8217;aprofitament o arrendament d&#8217;aquests b\u00e9ns.<\/li>\n<li><strong>Reforma d&#8217;habitatges<\/strong>: S&#8217;intensificar\u00e0 el control sobre les activitats de rehabilitaci\u00f3 i reformes d&#8217;habitatge.<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/03\/Inspector.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-7228\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/03\/Inspector.png\" alt=\"\" width=\"634\" height=\"640\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/03\/Inspector.png 634w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/03\/Inspector-297x300.png 297w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/03\/Inspector-150x150.png 150w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/>bu<\/a><\/p>\n<h3><em><span style=\"color: #3366ff;\">Som assessors fiscals. Consulteu-nos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.<\/span> <\/em><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Entre les principals l\u00ednies d&#8217;actuaci\u00f3 del Pla Anual de Control Tributari i Duaner de 2023, Hisenda posar\u00e0 el focus a detectar l\u2019economia submergida, especialment en el sector de la rehabilitaci\u00f3 i les reformes d&#8217;immobles, aix\u00ed com per a la identificaci\u00f3 de programari d&#8217;ocultaci\u00f3 de vendes, i es refor\u00e7ar\u00e0 el control sobre cobraments virtuals a trav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":719,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,16],"tags":[2489,2490,2491],"class_list":["post-7223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-fiscal-i-comptable","tag-control-impostos-2023","tag-inspeccions-hisenda-2023","tag-pla-inspeccio-hisenda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>On posar\u00e0 el focus Hisenda en el 2023? | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"On posar\u00e0 el focus Hisenda en el 2023? | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Entre les principals l\u00ednies d&#8217;actuaci\u00f3 del Pla Anual de Control Tributari i Duaner de 2023, Hisenda posar\u00e0 el focus a detectar l\u2019economia submergida, especialment en el sector de la rehabilitaci\u00f3 i les reformes d&#8217;immobles, aix\u00ed com per a la identificaci\u00f3 de programari d&#8217;ocultaci\u00f3 de vendes, i es refor\u00e7ar\u00e0 el control sobre cobraments virtuals a trav\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-13T10:03:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/fiscalcomptable1_2446638.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"On posar\u00e0 el focus Hisenda en el 2023?\",\"datePublished\":\"2023-03-13T10:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/\"},\"wordCount\":547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/fiscalcomptable1_2446638.jpg\",\"keywords\":[\"control impostos 2023\",\"Inspeccions Hisenda 2023\",\"pla inspecci\u00f3 hisenda\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Fiscal i comptable\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/\",\"name\":\"On posar\u00e0 el focus Hisenda en el 2023? | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/fiscalcomptable1_2446638.jpg\",\"datePublished\":\"2023-03-13T10:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/fiscalcomptable1_2446638.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/fiscalcomptable1_2446638.jpg\",\"width\":658,\"height\":325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/on-posara-el-focus-hisenda-en-el-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"On posar\u00e0 el focus Hisenda en el 2023?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"On posar\u00e0 el focus Hisenda en el 2023? | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/","og_locale":"en_US","og_type":"article","og_title":"On posar\u00e0 el focus Hisenda en el 2023? | RM Assessors","og_description":"Entre les principals l\u00ednies d&#8217;actuaci\u00f3 del Pla Anual de Control Tributari i Duaner de 2023, Hisenda posar\u00e0 el focus a detectar l\u2019economia submergida, especialment en el sector de la rehabilitaci\u00f3 i les reformes d&#8217;immobles, aix\u00ed com per a la identificaci\u00f3 de programari d&#8217;ocultaci\u00f3 de vendes, i es refor\u00e7ar\u00e0 el control sobre cobraments virtuals a trav\u00e9s [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2023-03-13T10:03:43+00:00","og_image":[{"width":658,"height":325,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/fiscalcomptable1_2446638.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"On posar\u00e0 el focus Hisenda en el 2023?","datePublished":"2023-03-13T10:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/"},"wordCount":547,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/fiscalcomptable1_2446638.jpg","keywords":["control impostos 2023","Inspeccions Hisenda 2023","pla inspecci\u00f3 hisenda"],"articleSection":["Butllet\u00ed mensual","Destacats","Fiscal i comptable"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/","url":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/","name":"On posar\u00e0 el focus Hisenda en el 2023? | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/fiscalcomptable1_2446638.jpg","datePublished":"2023-03-13T10:03:43+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/fiscalcomptable1_2446638.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/fiscalcomptable1_2446638.jpg","width":658,"height":325},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/on-posara-el-focus-hisenda-en-el-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"On posar\u00e0 el focus Hisenda en el 2023?"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/7223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=7223"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/7223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=7223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=7223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=7223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}