{"id":7552,"date":"2017-12-21T13:40:09","date_gmt":"2017-12-21T11:40:09","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/festes-locals-de-la-demarcacio-de-girona-el-2018\/"},"modified":"2017-12-21T13:40:09","modified_gmt":"2017-12-21T11:40:09","slug":"festes-locals-de-la-demarcacio-de-girona-el-2018","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/","title":{"rendered":"Festes locals de la demarcaci\u00f3 de Girona el 2018."},"content":{"rendered":"<p>Informem tot seguit de les dates de les fetes locals pel 2018 en algunes de les poblacions m\u00e9s importants de la demarcaci\u00f3 de Girona:<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Comarca de l&#8217;Alt Empord\u00e0:<\/strong><\/span><\/p>\n<ul>\n<li>B\u00e0scara, 19 d\u2019abril i 1 d\u2019agost<\/li>\n<li>Cadaqu\u00e9s, 14 de febrer i 18 de desembre<\/li>\n<li>Cantallops, 14 de maig i 20 d\u2019agost<\/li>\n<li>Capmany, 13 de febrer i 21 de maig<\/li>\n<li>Castell\u00f3 d\u2019Emp\u00faries, 2 de febrer i 10 d\u2019agost.<\/li>\n<li>Colera, 8 de maig i 1 d\u2019octubre<\/li>\n<li><strong>Figueres<\/strong> 3 de maig 29 de juny.<\/li>\n<li>Garriguella, 20 d\u2019agost i 10 de desembre<\/li>\n<li>Jonquera, la, 21 de maig i 8 de setembre<\/li>\n<li>L\u2019Escala 29 de juny 16 de juliol<\/li>\n<li>Llan\u00e7\u00e0 22 de gener 16 de juliol.<\/li>\n<li>Mollet de Peralada, 7 d\u2019abril i 6 d\u2019agost<\/li>\n<li>Navata, 3 de maig i 29 de juny<\/li>\n<li>Peralada, 30 d\u2019abril i 2 de novembre<\/li>\n<li>Port de la Selva, el, 21 de maig i 6 d\u2019agost<\/li>\n<li>Portbou, 8 de gener i 25 de juliol<\/li>\n<li>Roses 9 de febrer 12 de febrer<\/li>\n<li>Sant Pere Pescador, 19 de gener i 29 de juny<\/li>\n<li>Vilabertran, 3 de maig i 29 de juny<\/li>\n<li>Viladamat, 27 de juliol i 7 de desembre<\/li>\n<li>Vilafant, 3 de maig i 29 de juny<\/li>\n<li>Vilaju\u00efga, 22 de gener i 30 de juliol<\/li>\n<li>Vilamalla, 3 de maig i 29 de juny<\/li>\n<\/ul>\n<p><strong><span style=\"color: #ff0000;\">Comarca del Baix Empord\u00e0:<\/span><\/strong><\/p>\n<ul>\n<li>Calonge 16 de juliol 12 de novembre.<\/li>\n<li>Castell-Platja d\u2019Aro 8 de febrer 8 de setembre.<\/li>\n<li><strong>La Bisbal d\u2019Empord\u00e0<\/strong> 21 de maig 16 d\u2019agost.<\/li>\n<li>Palafrugell 21 de maig 20 de juliol<\/li>\n<li>Palam\u00f3s 25 de juny 26 de juny<\/li>\n<li>St. Antoni de Calonge 13 de juny 31 d\u2019agost<\/li>\n<li>St. Feliu de Gu\u00edxols 9 de febrer 1 d\u2019agost<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Comarca de La Cerdanya:<\/strong> <\/span><\/p>\n<ul>\n<li><strong>Puigcerd\u00e0<\/strong> 16 de juliol 8 de setembre.<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Comarca de La Carrotxa:<\/strong> <\/span><\/p>\n<ul>\n<li>Argelaguer, 14 de maig i 10 de desembre<\/li>\n<li>Besal\u00fa, 23 de mar\u00e7 i 21 de setembre<\/li>\n<li>Castellfollit de la Roca, 21 de maig i 17 de setembre<\/li>\n<li>Mai\u00e0 de Montcal, 22 de gener i 21 de maig<\/li>\n<li><strong>Olot<\/strong> 8 de setembre 10 de setembre.<\/li>\n<li>Planes d\u2019Hostoles, les, 25 de juliol i 24 de setembre<\/li>\n<li>Preses, les, 10 de setembre i 11 d\u2019octubre.<\/li>\n<li>Sant Aniol de Finestres, 30 de juliol i 13 de desembre<\/li>\n<li>Sant Feliu de Pallerols, 21 de maig i 1 d\u2019agost<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Comarca del Giron\u00e8s:<\/strong> <\/span><\/p>\n<ul>\n<li>Bescan\u00f3, 10 d\u2019agost i 29 d\u2019octubre<\/li>\n<li>Bordils, 20 d\u2019agost i 29 d\u2019octubre<\/li>\n<li>Canet d\u2019Adri, 1 d\u2019octubre i 29 d\u2019octubre<\/li>\n<li>Cass\u00e0 de la Selva, 28 de maig i 29 de maig<\/li>\n<li>Celr\u00e0, 7 de maig i 29 d\u2019octubre<\/li>\n<li>Cervi\u00e0 de Ter, 25 d\u2019agost i 29 d\u2019octubre<\/li>\n<li>Fornells de la Selva, 25 de juliol i 29 d\u2019octubre<\/li>\n<li><strong>Girona<\/strong> 25 de juliol 29 d\u2019octubre<\/li>\n<li>Llagostera 21 de maig 22 de maig<\/li>\n<li>Quart, 25 de juliol i 29 d\u2019octubre<\/li>\n<li>Salt 25 de juliol 29 d\u2019octubre<\/li>\n<li>Sant Gregori, 16 de juliol i 29 d\u2019octubre<\/li>\n<li>Sarri\u00e0 de Ter, 25 de juliol i 29 d\u2019octubre.<\/li>\n<li>Vilablareix, 25 de juliol i 29 d\u2019octubre<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Comarca del Pla de l&#8217;Estany<\/strong>:<\/span><\/p>\n<ul>\n<li><strong>Banyoles<\/strong> 16 d\u2019agost 22 d\u2019octubre<\/li>\n<li>Cornell\u00e0 del Terri, 29 de juny i 22 d\u2019octubre<\/li>\n<li>Crespi\u00e0, 26 de febrer i 10 de desembre<\/li>\n<li>Esponell\u00e0, 5 de febrer i 22 d\u2019octubre<\/li>\n<li>Fontcoberta, 3 d\u2019agost i 22 d\u2019octubre<\/li>\n<li>Palol de Revardit, 22 d\u2019octubre i 29 d\u2019octubre<\/li>\n<li>Porqueres, 21 de maig i 7 de desembre<\/li>\n<li>Sant Miquel de Campmajor, 5 de febrer i 29 de setembre<\/li>\n<li>Seriny\u00e0, 22 d\u2019octubre i 3 de desembre<\/li>\n<li>Vilademuls, 26 de gener i 22 d\u2019octubre<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Comarca de Ripoll\u00e8s:<\/strong><\/span><\/p>\n<ul>\n<li><strong>Ripoll<\/strong> 10 de maig 11 de maig<\/li>\n<li>St. Joan les Abadesses 29 de juny 10 de setembre<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Comarca de La Selva:<\/strong> <\/span><\/p>\n<ul>\n<li>Amer, 23 de mar\u00e7 i 16 d\u2019agost<\/li>\n<li>Angl\u00e8s, 21 de maig i 3 de setembre<\/li>\n<li>Arb\u00facies, 1 de juny i 30 de juliol<\/li>\n<li>Blanes 3 d\u2019abril 26 de juliol<\/li>\n<li>Breda, 7 de setembre i 10 de setembre<\/li>\n<li>Caldes de Malavella, 6 d\u2019agost i 22 de setembre<\/li>\n<li>Cellera de Ter, la, 23 d\u2019abril i 2 de novembre<\/li>\n<li>Hostalric, 9 de juliol i 1 d\u2019octubre<\/li>\n<li>Lloret de Mar 24 de juliol 19 de novembre<\/li>\n<li>Ma\u00e7anet de la Selva, 2 de maig i 10 d\u2019agost<\/li>\n<li>Riudarenes, 17 de setembre i 9 de novembre<\/li>\n<li>Riudellots de la Selva, 30 d\u2019abril i 29 d\u2019octubre<\/li>\n<li>Sant Feliu de Buixalleu, 29 de mar\u00e7 i 10 d\u2019agost<\/li>\n<li>Sant Hilari Sacalm, 21 de maig i 24 d\u2019agost<\/li>\n<li>Sant Juli\u00e0 del Llor i Bonmat\u00ed, 23 d\u2019abril i 21 de maig<\/li>\n<li><strong>Sta. Coloma de Farners<\/strong> 3 d\u2019abril 24 de setembre<\/li>\n<li>Sils, 26 de setembre i 28 de setembre<\/li>\n<li>Tossa de Mar, 22 de gener i 29 de juny<\/li>\n<li>Vidreres, 13 de febrer i 3 de setembre<\/li>\n<li>Vilob\u00ed d\u2019Onyar, 29 de mar\u00e7 i 20 de juliol<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/administracions5_174133991.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-754\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/administracions5_174133991-300x148.jpg\" alt=\"\" width=\"300\" height=\"148\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/administracions5_174133991-300x148.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/administracions5_174133991.jpg 658w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><span style=\"color: #3366ff;\"><em><strong>Som assessors laborals i de la Seguretat Social. Consulteu-nos sense comprom\u00eds trucant al 972 426 083 o per correu electr\u00f2nic adre\u00e7at a laboral@rm-assessors.cat<\/strong><\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informem tot seguit de les dates de les fetes locals pel 2018 en algunes de les poblacions m\u00e9s importants de la demarcaci\u00f3 de Girona: Comarca de l&#8217;Alt Empord\u00e0: B\u00e0scara, 19 d\u2019abril i 1 d\u2019agost Cadaqu\u00e9s, 14 de febrer i 18 de desembre Cantallops, 14 de maig i 20 d\u2019agost Capmany, 13 de febrer i 21 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[41,16,11],"tags":[848,840,849],"class_list":["post-7552","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacats","category-fiscal-i-comptable","category-laboral","tag-calendari-festes-locals","tag-festes-locals-2018","tag-festes-locals-girona"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Festes locals de la demarcaci\u00f3 de Girona el 2018. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Festes locals de la demarcaci\u00f3 de Girona el 2018. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Informem tot seguit de les dates de les fetes locals pel 2018 en algunes de les poblacions m\u00e9s importants de la demarcaci\u00f3 de Girona: Comarca de l&#8217;Alt Empord\u00e0: B\u00e0scara, 19 d\u2019abril i 1 d\u2019agost Cadaqu\u00e9s, 14 de febrer i 18 de desembre Cantallops, 14 de maig i 20 d\u2019agost Capmany, 13 de febrer i 21 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-21T11:40:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors11_60092652.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Festes locals de la demarcaci\u00f3 de Girona el 2018.\",\"datePublished\":\"2017-12-21T11:40:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/\"},\"wordCount\":686,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/rmassessors11_60092652.jpg\",\"keywords\":[\"calendari festes locals\",\"festes locals 2018\",\"festes locals girona\"],\"articleSection\":[\"Destacats\",\"Fiscal i comptable\",\"Laboral\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/\",\"name\":\"Festes locals de la demarcaci\u00f3 de Girona el 2018. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/rmassessors11_60092652.jpg\",\"datePublished\":\"2017-12-21T11:40:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/rmassessors11_60092652.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/rmassessors11_60092652.jpg\",\"width\":658,\"height\":325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/festes-locals-de-la-demarcacio-de-girona-el-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Festes locals de la demarcaci\u00f3 de Girona el 2018.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/en\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Festes locals de la demarcaci\u00f3 de Girona el 2018. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/","og_locale":"en_US","og_type":"article","og_title":"Festes locals de la demarcaci\u00f3 de Girona el 2018. | RM Assessors","og_description":"Informem tot seguit de les dates de les fetes locals pel 2018 en algunes de les poblacions m\u00e9s importants de la demarcaci\u00f3 de Girona: Comarca de l&#8217;Alt Empord\u00e0: B\u00e0scara, 19 d\u2019abril i 1 d\u2019agost Cadaqu\u00e9s, 14 de febrer i 18 de desembre Cantallops, 14 de maig i 20 d\u2019agost Capmany, 13 de febrer i 21 [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2017-12-21T11:40:09+00:00","og_image":[{"width":658,"height":325,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors11_60092652.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Written by":"neorg_US","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Festes locals de la demarcaci\u00f3 de Girona el 2018.","datePublished":"2017-12-21T11:40:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/"},"wordCount":686,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors11_60092652.jpg","keywords":["calendari festes locals","festes locals 2018","festes locals girona"],"articleSection":["Destacats","Fiscal i comptable","Laboral"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/","url":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/","name":"Festes locals de la demarcaci\u00f3 de Girona el 2018. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors11_60092652.jpg","datePublished":"2017-12-21T11:40:09+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors11_60092652.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/rmassessors11_60092652.jpg","width":658,"height":325},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/en\/festes-locals-de-la-demarcacio-de-girona-el-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Festes locals de la demarcaci\u00f3 de Girona el 2018."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/en\/#website","url":"https:\/\/www.rm-assessors.cat\/en\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/en\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/en\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/7552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/comments?post=7552"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/posts\/7552\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/media?parent=7552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/categories?post=7552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/en\/wp-json\/wp\/v2\/tags?post=7552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}