{"id":12831,"date":"2024-08-06T13:24:09","date_gmt":"2024-08-06T11:24:09","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/?p=12831"},"modified":"2024-08-06T13:24:09","modified_gmt":"2024-08-06T11:24:09","slug":"responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/","title":{"rendered":"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci."},"content":{"rendered":"<p>En un article anterior v\u00e0rem analitzar la responsabilitat de l&#8217;adquirent en un trasp\u00e0s de negoci. Ara destacarem quines son les responsabilitats del cedent en relaci\u00f3 als deutes amb Hisenda i Seguretat Social anteriors a la transmissi\u00f3<\/p>\n<hr \/>\n<h3>Deutes tributaris<\/h3>\n<p>Es d&#8217;aplicaci\u00f3 l&#8217;article 42.c de la<em><span style=\"color: #ff0000;\"><a style=\"color: #ff0000;\" href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2003-23186\"> Llei General Tribut\u00e0ria<\/a> <\/span><\/em>que preveu la responsabilitat solid\u00e0ria del cedent i de l&#8217;adquirent en la successi\u00f3 en la titularitat o en l&#8217;exercici de l&#8217;activitat transmesa, per obligacions tribut\u00e0ries de l&#8217;anterior titular derivades de l&#8217;exercici de l&#8217;activitat.<\/p>\n<p>D&#8217;altra banda, l&#8217;art. 175.2 de la mateixa Llei General Tribut\u00e0ria preveu que el qui es proposi adquirir un negoci pot demanar a l&#8217;Administraci\u00f3, amb la conformitat del cedent, un certificat de deutes pendents , que se l&#8217;hi haur\u00e0 d&#8217;expedir en el termini de tres mesos. En tal cas l&#8217;adquirent sols respondr\u00e0 dels deutes que constin en el certificat.<\/p>\n<p>En conseq\u00fc\u00e8ncia:<\/p>\n<ul>\n<li><strong>Responsabilitat solid\u00e0ria de cedent i adquirent: <\/strong>Dels deutes tributaris anteriors al trasp\u00e0s de negoci derivats de l&#8217;exercici de l&#8217;activitat\u00a0en responen tant el cedent com l&#8217;adquirent. Per tant, tots dos es consideren deutors i l&#8217;Ag\u00e8ncia Tribut\u00e0ria els pot obligar a pagar la totalitat del deute a qualsevol d&#8217;ells. Aquesta responsabilitat tamb\u00e9 s&#8217;est\u00e9n a falta d&#8217;ingr\u00e9s de les retencions i pagaments a compte.<\/li>\n<li><strong>Responsabilitat exclusiva del cedent:<\/strong>\n<ul>\n<li>La responsabilitat de l&#8217;adquirent quedar\u00e0 exclosa en relaci\u00f3 als deutes que no figurin en el certificat de deutes pendents que hagu\u00e9s demanat, o en relaci\u00f3 a la totalitat del deute si el certificat no l&#8217;hi hagu\u00e9s estat expedit en el termini de tres mesos.<\/li>\n<li>Els adquirents d&#8217;elements a\u00efllats d&#8217;un negoci tampoc seran responsables, excepte que aquestes adquisicions, encara que haguessin estat fetes per una o m\u00e9s persones o entitats, permetin la continuaci\u00f3 de l&#8217;explotaci\u00f3 o activitat.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3>Deutes per salaris i Seguretat Social<\/h3>\n<p>Com en el cas anterior, l&#8217;art, 44,1 de la <span style=\"color: #ff0000;\"><em><a style=\"color: #ff0000;\" href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2015-11724\">Llei General de la Seguretat Social<\/a><\/em><\/span>, preveu la responsabilitat solid\u00e0ria del cedent i de l&#8217;adquirent en el trasp\u00e0s d&#8217;una empresa, un centre de treball o una unitat productiva aut\u00f2noma que mantingui la seva identitat.<\/p>\n<p>En conseq\u00fc\u00e8ncia:<\/p>\n<ul>\n<li><strong>Responsabilitat solid\u00e0ria de cedent i adquirent<\/strong>: Del pagament de les prestacions causades\u00a0 i de les cotitzacions en descobert anteriors a la successi\u00f3, en responen tant el cedent com l&#8217;adquirent. Per tant, tots dos es consideren deutors i es\u00a0 podr\u00e0 obligar a pagar la totalitat del deute a qualsevol d&#8217;ells.<\/li>\n<li><strong>Certificaci\u00f3 negativa de deutes amb la Seguretat Social<\/strong>: En aquest cas, el certificat de la Tresoreria de la Seguretat Social de que no hi ha deutes pendents no exonera de responsabilitat l&#8217;empresa adquirent ja que poden existir deutes ajornats sobre els que la Tresoreria encara no hagi iniciat la reclamaci\u00f3.<\/li>\n<\/ul>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-232\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/01\/about-img-01@2x-300x231.jpeg\" alt=\"\" width=\"300\" height=\"231\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/01\/about-img-01@2x-300x231.jpeg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/01\/about-img-01@2x-600x462.jpeg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/01\/about-img-01@2x-1024x789.jpeg 1024w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/01\/about-img-01@2x-768x591.jpeg 768w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/01\/about-img-01@2x.jpeg 1170w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h3><span style=\"color: #3366ff;\"><em>Som assessors fiscals i laborals. Consulteu-nos sense comprom\u00eds trucant al 972 08 258, o per correu electr\u00f2nic adre\u00e7at a info@m-assessors.cat.<\/em><\/span><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>En un article anterior v\u00e0rem analitzar la responsabilitat de l&#8217;adquirent en un trasp\u00e0s de negoci. Ara destacarem quines son les responsabilitats del cedent en relaci\u00f3 als deutes amb Hisenda i Seguretat Social anteriors a la transmissi\u00f3 Deutes tributaris Es d&#8217;aplicaci\u00f3 l&#8217;article 42.c de la Llei General Tribut\u00e0ria que preveu la responsabilitat solid\u00e0ria del cedent i [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,15],"tags":[2885,2883,2884],"class_list":["post-12831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-rm-assessors","tag-responsabilitat-deutes-laborals","tag-responsabilitat-traspas-negoci","tag-responsable-deutes-tributaris"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"En un article anterior v\u00e0rem analitzar la responsabilitat de l&#8217;adquirent en un trasp\u00e0s de negoci. Ara destacarem quines son les responsabilitats del cedent en relaci\u00f3 als deutes amb Hisenda i Seguretat Social anteriors a la transmissi\u00f3 Deutes tributaris Es d&#8217;aplicaci\u00f3 l&#8217;article 42.c de la Llei General Tribut\u00e0ria que preveu la responsabilitat solid\u00e0ria del cedent i [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-06T11:24:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/05\/1p01exels-photo-7089401_1714645713image.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Albert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Albert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/\"},\"author\":{\"name\":\"Albert\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\"},\"headline\":\"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci.\",\"datePublished\":\"2024-08-06T11:24:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/\"},\"wordCount\":521,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1p01exels-photo-7089401_1714645713image.jpeg\",\"keywords\":[\"responsabilitat deutes laborals\",\"responsabilitat trasp\u00e0s negoci\",\"responsable deutes tributaris\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/\",\"name\":\"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1p01exels-photo-7089401_1714645713image.jpeg\",\"datePublished\":\"2024-08-06T11:24:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1p01exels-photo-7089401_1714645713image.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/1p01exels-photo-7089401_1714645713image.jpeg\",\"width\":810,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\",\"name\":\"Albert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"caption\":\"Albert\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/","og_locale":"es_ES","og_type":"article","og_title":"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci. | RM Assessors","og_description":"En un article anterior v\u00e0rem analitzar la responsabilitat de l&#8217;adquirent en un trasp\u00e0s de negoci. Ara destacarem quines son les responsabilitats del cedent en relaci\u00f3 als deutes amb Hisenda i Seguretat Social anteriors a la transmissi\u00f3 Deutes tributaris Es d&#8217;aplicaci\u00f3 l&#8217;article 42.c de la Llei General Tribut\u00e0ria que preveu la responsabilitat solid\u00e0ria del cedent i [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2024-08-06T11:24:09+00:00","og_image":[{"width":810,"height":450,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/05\/1p01exels-photo-7089401_1714645713image.jpeg","type":"image\/jpeg"}],"author":"Albert","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"Albert","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/"},"author":{"name":"Albert","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b"},"headline":"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci.","datePublished":"2024-08-06T11:24:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/"},"wordCount":521,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/05\/1p01exels-photo-7089401_1714645713image.jpeg","keywords":["responsabilitat deutes laborals","responsabilitat trasp\u00e0s negoci","responsable deutes tributaris"],"articleSection":["Butllet\u00ed mensual","Destacats","RM-Assessors"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/","url":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/","name":"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/05\/1p01exels-photo-7089401_1714645713image.jpeg","datePublished":"2024-08-06T11:24:09+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/05\/1p01exels-photo-7089401_1714645713image.jpeg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2024\/05\/1p01exels-photo-7089401_1714645713image.jpeg","width":810,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/responsabilitat-del-cedent-en-front-hisenda-i-seguretat-social-en-un-traspas-de-negoci\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Responsabilitat del cedent en front Hisenda i Seguretat Social en un trasp\u00e0s de negoci."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b","name":"Albert","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","caption":"Albert"},"sameAs":["https:\/\/www.rm-assessors.cat\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/12831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=12831"}],"version-history":[{"count":3,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/12831\/revisions"}],"predecessor-version":[{"id":12836,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/12831\/revisions\/12836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/12268"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=12831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=12831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=12831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}