{"id":13862,"date":"2025-05-23T12:54:10","date_gmt":"2025-05-23T10:54:10","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/?p=13862"},"modified":"2025-05-23T12:54:10","modified_gmt":"2025-05-23T10:54:10","slug":"hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/","title":{"rendered":"Hem ampliat les oficines centrals de RM Assessors a Girona"},"content":{"rendered":"<p class=\"cs95E872D0\"><span class=\"cs9D249CCB\"><span>La direcci\u00f3 i equip de RM Assessors es complau en informar-vos que a partir del proper 2 de juny disposarem d&#8217;un nou espai al costat de les nostres oficines habituals centrals de Girona per tal de continuar millorant l&#8217;atenci\u00f3 i el servei que oferim a tots els nostres clients.<\/span><\/p>\n<p><span>D\u00b4aquesta forma farem efectiva l&#8217;ampliaci\u00f3 de les nostres instal\u00b7lacions amb l&#8217;obertura d&#8217;un nou local de m\u00e9s de 220 metres quadrats situat a Gran Via Jaume I, n\u00famero 12, de Girona. Aquest nou espai acollir\u00e0 el Departament Jur\u00eddic, on disposarem d&#8217;una recepci\u00f3 pr\u00f2pia i tamb\u00e9 de sales de reunions per atendre-us.<\/span><\/span><\/p>\n<p class=\"cs95E872D0\"><span class=\"cs9D249CCB\"><br \/>\n<span>Paral\u00b7lelament, el Departament de Finques i Administraci\u00f3 de Comunitats es traslladar\u00e0 a una nova ubicaci\u00f3 que es troba en aquest mateix local amb acc\u00e9s al carrer Figuerola, n\u00famero 13, per una major comoditat dels clients que s\u00b4adrecin a aquest departament.<\/span><\/span><\/p>\n<p class=\"cs95E872D0\"><span class=\"cs9D249CCB\"><br \/>\n<span>La resta d&#8217;equips i departaments (fiscal, comptabilitat, laboral i assegurances) es mantindran a la seva ubicaci\u00f3 habitual de Gran Via Jaume I, n\u00famero 14.<\/span><\/span><\/p>\n<p class=\"cs95E872D0\"><span class=\"cs9D249CCB\"><br \/>\n<span>Mantenim els n\u00fameros de tel\u00e8fons, les adreces de correu electr\u00f2nic i totes les funcionalitats habituals. Aquesta millora t\u00e9 com a objectiu ampliar espais, optimitzar la distribuci\u00f3 interna del nostre equip i oferir un entorn m\u00e9s modern, amable, eficient i sostenible, tant per al nostre equip com per a totes les persones, empreses i col\u00b7laboradors que confiem en nosaltres.<\/span><\/span><\/p>\n<p class=\"cs95E872D0\"><span class=\"cs9D249CCB\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-13856\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image3-1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image3-1-300x225.jpeg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image3-1-600x450.jpeg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image3-1.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><br \/>\n<span>Gr\u00e0cies per la vostra confian\u00e7a.<\/span><\/span><\/p>\n<p class=\"cs95E872D0\"><span class=\"cs9D249CCB\"><span>L&#8217;equip d&#8217;assessors de RM<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La direcci\u00f3 i equip de RM Assessors es complau en informar-vos que a partir del proper 2 de juny disposarem d&#8217;un nou espai al costat de les nostres oficines habituals centrals de Girona per tal de continuar millorant l&#8217;atenci\u00f3 i el servei que oferim a tots els nostres clients. D\u00b4aquesta forma farem efectiva l&#8217;ampliaci\u00f3 de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[41,15],"tags":[3089,3090,3091],"class_list":["post-13862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacats","category-rm-assessors","tag-ampliacio-oficines-girona","tag-ampliacio-rm-assessors","tag-noves-oficines-girona"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hem ampliat les oficines centrals de RM Assessors a Girona | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hem ampliat les oficines centrals de RM Assessors a Girona | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"La direcci\u00f3 i equip de RM Assessors es complau en informar-vos que a partir del proper 2 de juny disposarem d&#8217;un nou espai al costat de les nostres oficines habituals centrals de Girona per tal de continuar millorant l&#8217;atenci\u00f3 i el servei que oferim a tots els nostres clients. D\u00b4aquesta forma farem efectiva l&#8217;ampliaci\u00f3 de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T10:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image5-1-rotated.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Albert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Albert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/\"},\"author\":{\"name\":\"Albert\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\"},\"headline\":\"Hem ampliat les oficines centrals de RM Assessors a Girona\",\"datePublished\":\"2025-05-23T10:54:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image5-1-rotated.jpeg\",\"keywords\":[\"ampliaci\u00f3 oficines Girona\",\"ampliaci\u00f3 RM Assessors\",\"noves oficines Girona\"],\"articleSection\":[\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/\",\"name\":\"Hem ampliat les oficines centrals de RM Assessors a Girona | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image5-1-rotated.jpeg\",\"datePublished\":\"2025-05-23T10:54:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image5-1-rotated.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/image5-1-rotated.jpeg\",\"width\":480,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hem ampliat les oficines centrals de RM Assessors a Girona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/42246d1219a452b532cb27cbc0fa609b\",\"name\":\"Albert\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g\",\"caption\":\"Albert\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hem ampliat les oficines centrals de RM Assessors a Girona | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/","og_locale":"es_ES","og_type":"article","og_title":"Hem ampliat les oficines centrals de RM Assessors a Girona | RM Assessors","og_description":"La direcci\u00f3 i equip de RM Assessors es complau en informar-vos que a partir del proper 2 de juny disposarem d&#8217;un nou espai al costat de les nostres oficines habituals centrals de Girona per tal de continuar millorant l&#8217;atenci\u00f3 i el servei que oferim a tots els nostres clients. D\u00b4aquesta forma farem efectiva l&#8217;ampliaci\u00f3 de [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2025-05-23T10:54:10+00:00","og_image":[{"width":480,"height":640,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image5-1-rotated.jpeg","type":"image\/jpeg"}],"author":"Albert","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"Albert","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/"},"author":{"name":"Albert","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b"},"headline":"Hem ampliat les oficines centrals de RM Assessors a Girona","datePublished":"2025-05-23T10:54:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image5-1-rotated.jpeg","keywords":["ampliaci\u00f3 oficines Girona","ampliaci\u00f3 RM Assessors","noves oficines Girona"],"articleSection":["Destacats","RM-Assessors"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/","url":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/","name":"Hem ampliat les oficines centrals de RM Assessors a Girona | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image5-1-rotated.jpeg","datePublished":"2025-05-23T10:54:10+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image5-1-rotated.jpeg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2025\/05\/image5-1-rotated.jpeg","width":480,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/hem-ampliat-les-oficines-centrals-de-rm-assessors-a-girona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Hem ampliat les oficines centrals de RM Assessors a Girona"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/42246d1219a452b532cb27cbc0fa609b","name":"Albert","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c0cd47d854fae6e32b371367d089af02af9d81a9a0de2cd29aba9c75da919c49?s=96&d=mm&r=g","caption":"Albert"},"sameAs":["https:\/\/www.rm-assessors.cat\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/13862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=13862"}],"version-history":[{"count":1,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/13862\/revisions"}],"predecessor-version":[{"id":13863,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/13862\/revisions\/13863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/13859"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=13862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=13862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=13862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}