{"id":3609,"date":"2019-07-05T10:06:48","date_gmt":"2019-07-05T08:06:48","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/"},"modified":"2019-07-05T10:06:48","modified_gmt":"2019-07-05T08:06:48","slug":"suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/","title":{"rendered":"Suspensi\u00f3 del contracte de treball per mutu acord de les parts"},"content":{"rendered":"<p>l&#8217;Art. 45 de l&#8217;Estatut dels Treballadors estableix les causes legals de suspensi\u00f3 del contracte de treball. Destaquem el seg\u00fcent:<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Causes legals de suspensi\u00f3 del contracte de treball<\/strong><\/span>:<\/p>\n<ul>\n<li>Mutu acord de les parts.<\/li>\n<li>Les consignades v\u00e0lidament en el contracte.<\/li>\n<li>Altres causes legals, com ara la incapacitat temporal dels treballadors, naixement de fills, risc d&#8217;embar\u00e0s, etc.<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Moment en el que empresa i treballador poden acordar la suspensi\u00f3 del contracte de treball<\/strong><\/span>:<\/p>\n<ul>\n<li>Inicialment, en el moment de fer el contracte de treball, empresa i treballador podran preveure les causes que si es donessin en el futur comportarien la suspensi\u00f3 del contracte.<\/li>\n<li>I tamb\u00e9 en qualsevol moment posterior.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Efectes i durada de la suspensi\u00f3 del contracte de treball per acord entre empresa i treballador: <\/strong><\/span><\/p>\n<ul>\n<li>El treballador no haur\u00e0 de treballar i l&#8217;empresa tampoc haur\u00e0 de pagar el salari.<\/li>\n<li>L&#8217;empresa tampoc haur\u00e0 de cotitzara a la Seguretat Social a no ser que s&#8217;hagu\u00e9s pactat el contrari.<\/li>\n<li>Empresa i treballador podran acordar lliurament la durada de la suspensi\u00f3 del contracte de treball.<\/li>\n<li>Es pot pactar que la suspensi\u00f3 sigui amb reserva del lloc de treball, o no. En el cas que s&#8217;hagu\u00e9s pactat de forma expressa la reserva del lloc de treball, la negativa de l&#8217;ocupador a la readmissi\u00f3 despr\u00e9s de la finalitzaci\u00f3 del per\u00edode suspensiu equivaldr\u00e0 a un acomiadament improcedent (com ha assenyalat el Tribunal Suprem en la seva sent\u00e8ncia de 26-10-2016).<\/li>\n<li>Les parts podran establir motius de suspensi\u00f3 del contracte sempre que no suposin ab\u00fas de dret. Les condicions de la suspensi\u00f3 s\u2019han d&#8217;establir per escrit. Excepte pacte en contrari l&#8217;empresari estar\u00e0 exempt de cotitzar a la Seguretat Social durant aquest per\u00edode.<\/li>\n<li>El que no es pot fer \u00e9s utilitzar el mutu acord per a establir un r\u00e8gim diferent d&#8217;algun sup\u00f2sit de suspensi\u00f3 que sigui menys favorable per al treballador que el legalment establert; jugaria en aquest cas el principi de irrenunciabilitat de drets.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Suspensi\u00f3 del contracte de treball durant del per\u00edode de prova<\/strong><\/span>:<\/p>\n<ul>\n<li>Durant el per\u00edode de prova, les situacions d&#8217;incapacitat temporal, naixement, risc durant l&#8217;embar\u00e0s, adopci\u00f3, guarda amb finalitats d&#8217;adopci\u00f3, acolliment, risc durant la lact\u00e0ncia i viol\u00e8ncia de g\u00e8nere que afectin la persona treballadora, interrompran el c\u00f2mput del per\u00edode de prova sempre que es produeixi acord entre les parts (art. 14.3 ET).<\/li>\n<li>La suspensi\u00f3 succe\u00efda durant la suspensi\u00f3 de un contracte temporal no implica la corresponent ampliaci\u00f3 de la durada del contracte, tret que aix\u00ed s&#8217;hagu\u00e9s pactat (art. 7 del RD 2720\/1998).<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-3355\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg\" alt=\"\" width=\"600\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><em><strong>Som assessors laborals i de la Seguretat Social. Consulteu-nos sense comprom\u00eds trucant al 972 4267 083, o per correu electr\u00f2nic adre\u00e7at a les nostres assessores laborals: rosaclara@rm-assessors.cat, o, montsepla@rm-assessors.cat.<\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>l&#8217;Art. 45 de l&#8217;Estatut dels Treballadors estableix les causes legals de suspensi\u00f3 del contracte de treball. Destaquem el seg\u00fcent: Causes legals de suspensi\u00f3 del contracte de treball: Mutu acord de les parts. Les consignades v\u00e0lidament en el contracte. Altres causes legals, com ara la incapacitat temporal dels treballadors, naixement de fills, risc d&#8217;embar\u00e0s, etc. Moment [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3360,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,11],"tags":[1293,1294,1295],"class_list":["post-3609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-laboral","tag-acord-suspensio-contracte","tag-causes-suspensio-contracte","tag-suspensio-contracte-treball"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suspensi\u00f3 del contracte de treball per mutu acord de les parts | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspensi\u00f3 del contracte de treball per mutu acord de les parts | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"l&#8217;Art. 45 de l&#8217;Estatut dels Treballadors estableix les causes legals de suspensi\u00f3 del contracte de treball. Destaquem el seg\u00fcent: Causes legals de suspensi\u00f3 del contracte de treball: Mutu acord de les parts. Les consignades v\u00e0lidament en el contracte. Altres causes legals, com ara la incapacitat temporal dels treballadors, naixement de fills, risc d&#8217;embar\u00e0s, etc. Moment [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-05T08:06:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Suspensi\u00f3 del contracte de treball per mutu acord de les parts\",\"datePublished\":\"2019-07-05T08:06:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/shutterstock_110539220.jpg\",\"keywords\":[\"acord suspensi\u00f3 contracte\",\"causes suspensi\u00f3 contracte\",\"suspensi\u00f3 contracte treball\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Laboral\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/\",\"name\":\"Suspensi\u00f3 del contracte de treball per mutu acord de les parts | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/shutterstock_110539220.jpg\",\"datePublished\":\"2019-07-05T08:06:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/shutterstock_110539220.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/shutterstock_110539220.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspensi\u00f3 del contracte de treball per mutu acord de les parts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspensi\u00f3 del contracte de treball per mutu acord de les parts | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/","og_locale":"es_ES","og_type":"article","og_title":"Suspensi\u00f3 del contracte de treball per mutu acord de les parts | RM Assessors","og_description":"l&#8217;Art. 45 de l&#8217;Estatut dels Treballadors estableix les causes legals de suspensi\u00f3 del contracte de treball. Destaquem el seg\u00fcent: Causes legals de suspensi\u00f3 del contracte de treball: Mutu acord de les parts. Les consignades v\u00e0lidament en el contracte. Altres causes legals, com ara la incapacitat temporal dels treballadors, naixement de fills, risc d&#8217;embar\u00e0s, etc. Moment [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2019-07-05T08:06:48+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Suspensi\u00f3 del contracte de treball per mutu acord de les parts","datePublished":"2019-07-05T08:06:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg","keywords":["acord suspensi\u00f3 contracte","causes suspensi\u00f3 contracte","suspensi\u00f3 contracte treball"],"articleSection":["Butllet\u00ed mensual","Destacats","Laboral"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/","url":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/","name":"Suspensi\u00f3 del contracte de treball per mutu acord de les parts | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg","datePublished":"2019-07-05T08:06:48+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2019\/03\/shutterstock_110539220.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/suspensio-del-contracte-de-treball-per-mutu-acord-de-les-parts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Suspensi\u00f3 del contracte de treball per mutu acord de les parts"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/3609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=3609"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/3609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/3360"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=3609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=3609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=3609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}