{"id":4667,"date":"2020-07-17T14:21:53","date_gmt":"2020-07-17T12:21:53","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/"},"modified":"2020-07-17T14:21:53","modified_gmt":"2020-07-17T12:21:53","slug":"ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/","title":{"rendered":"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball"},"content":{"rendered":"<div>La Generalitat de Catalunya acaba de modificar en el seg\u00fcent sentit els criteris pel que fa a l&#8217;\u00fas de la mascareta en els centres de treball:<strong><\/p>\n<p>En empreses no obertes al p\u00fablic, un cop la persona treballadora estigui al seu lloc de treball (asseguda i\/o fent una tasca que no comporti mobilitat) i amb totes les mesures necess\u00e0ries, pot prescindir de la mascareta malgrat que continua sent recomanable. En canvi, ser\u00e0 obligat\u00f2ria per a tots els despla\u00e7aments que es facin a l&#8217;interior del centre de treball (entrades, sortides, lavabo&#8230;)<\/p>\n<p>Tamb\u00e9 es podr\u00e0 prescindir de la mascareta en aquelles feines que impliquin un gran esfor\u00e7 f\u00edsic, independentment de si es duen a terme a l&#8217;interior o a l&#8217;exterior (per exemple, en treballs vinculats a la construcci\u00f3) i sempre que es pugui garantir la seva seguretat i salut.<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>EXCEPCIONS<\/strong><\/span><\/div>\n<ul>\n<li>En cas de dificultat respirat\u00f2ria que pugui agreujar-se pel seu \u00fas.<\/li>\n<li>Persones que ho tinguin contraindicat per ra\u00f3 de salut o discapacitat.<\/li>\n<li>Quan per la pr\u00f2pia naturalesa de les activitats l&#8217;\u00fas de la mascareta resulti incompatible.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #ff0000;\">M\u00c9S INFORMACI\u00d3<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/apigirona.us6.list-manage.com\/track\/click?u=c9fec421edc4397c1b3515da6&amp;id=47e70cacdf&amp;e=1758055e75\" target=\"_blank\" rel=\"noopener\">https:\/\/canalsalut.gencat.cat\/web\/.content\/_A-Z\/C\/coronavirus-2019-ncov\/material-divulgatiu\/faqs-us-mascareta.pdf<\/a><\/p>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4185\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\" alt=\"\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187-300x300.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><em><span style=\"color: #0000ff;\"><strong>Som assessors laborals i de la Seguretat Social. Consulteu-nos sense comprom\u00eds\u00a0 trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat<\/strong><\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Generalitat de Catalunya acaba de modificar en el seg\u00fcent sentit els criteris pel que fa a l&#8217;\u00fas de la mascareta en els centres de treball: En empreses no obertes al p\u00fablic, un cop la persona treballadora estigui al seu lloc de treball (asseguda i\/o fent una tasca que no comporti mobilitat) i amb totes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,11],"tags":[1659,1660,1609],"class_list":["post-4667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-laboral","tag-mascareta-centres-treball","tag-mascareta-feina","tag-us-obligatori-mascareta"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"La Generalitat de Catalunya acaba de modificar en el seg\u00fcent sentit els criteris pel que fa a l&#8217;\u00fas de la mascareta en els centres de treball: En empreses no obertes al p\u00fablic, un cop la persona treballadora estigui al seu lloc de treball (asseguda i\/o fent una tasca que no comporti mobilitat) i amb totes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-17T12:21:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball\",\"datePublished\":\"2020-07-17T12:21:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/\"},\"wordCount\":244,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1628196187.jpg\",\"keywords\":[\"mascareta centres treball\",\"mascareta feina\",\"\u00fas obligatori mascareta\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Laboral\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/\",\"name\":\"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1628196187.jpg\",\"datePublished\":\"2020-07-17T12:21:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1628196187.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1628196187.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/","og_locale":"es_ES","og_type":"article","og_title":"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball | RM Assessors","og_description":"La Generalitat de Catalunya acaba de modificar en el seg\u00fcent sentit els criteris pel que fa a l&#8217;\u00fas de la mascareta en els centres de treball: En empreses no obertes al p\u00fablic, un cop la persona treballadora estigui al seu lloc de treball (asseguda i\/o fent una tasca que no comporti mobilitat) i amb totes [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2020-07-17T12:21:53+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball","datePublished":"2020-07-17T12:21:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/"},"wordCount":244,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg","keywords":["mascareta centres treball","mascareta feina","\u00fas obligatori mascareta"],"articleSection":["Butllet\u00ed mensual","Destacats","Laboral"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/","url":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/","name":"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg","datePublished":"2020-07-17T12:21:53+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/ja-no-caldra-dur-la-mascareta-posada-en-tot-moment-en-els-centres-de-treball\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Ja no caldr\u00e0 dur la mascareta posada en tot moment en els centres de treball"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/4667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=4667"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/4667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/4185"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=4667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=4667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=4667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}