{"id":5629,"date":"2021-03-08T11:06:13","date_gmt":"2021-03-08T09:06:13","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/"},"modified":"2021-03-08T11:06:13","modified_gmt":"2021-03-08T09:06:13","slug":"covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/","title":{"rendered":"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">A partir del 8 de mar\u00e7, els bars i restaurants podran obrir de dos quarts de vuit del mat\u00ed fins a les cinc de la tarda. Fora d&#8217;aquesta franja hor\u00e0ria, els clients no podran romandre a l&#8217;establiment. El Govern mantindr\u00e0 set dies m\u00e9s, fins al 15 de mar\u00e7, el gruix de les mesures actuals per frenar la propagaci\u00f3 de la COVID-19, per\u00f2 flexibilitza les condicions de determinades activitats.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Us informem que el DOG del dissabte passat publica la <a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8358\/1839360.pdf\">RESOLUCI\u00d3 SLT\/612\/2021, de 5 de mar\u00e7<\/a>, per la qual es prorroguen i es modifiquen les mesures en mat\u00e8ria de salut p\u00fablica per a la contenci\u00f3 del brot epid\u00e8mic de la pand\u00e8mia de COVID-19 al territori de Catalunya. Destaquem el seg\u00fcent: <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Bars i restaurants: <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Podran obrir de dos quarts de vuit del mat\u00ed fins a les cinc de la tarda. Fora d&#8217;aquesta franja hor\u00e0ria, els clients no podran romandre a l&#8217;establiment. Es podr\u00e0 servir menjar per emportar. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0mbit esportiu<\/strong>:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Es mantenen les limitacions en aforaments i la cita pr\u00e8via, si b\u00e9 ara permetr\u00e0 la reobertura dels vestidors.<\/li><li>Es reprenen les lligues federatives regulars a partir dels 16 anys.<\/li><li>Totes les competicions s&#8217;hauran de celebrar sense p\u00fablic.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u00c0mbit universitari<\/strong>:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>La presencialitat a les universitats continuar\u00e0 reservada a les pr\u00e0ctiques i les avaluacions.<\/li><li>Es permetr\u00e0 la presencialitat simult\u00e0nia de fins a un m\u00e0xim del 30% dels universitaris de cada centre i no es podr\u00e0 superar aquest percentatge en cap universitat.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Activitats extraescolars<\/strong>:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Es podran realitzar, per\u00f2 mantenint els grups m\u00e0xims de 6 persones per aula en les etapes d&#8217;educaci\u00f3 infantil, prim\u00e0ria, i ara tamb\u00e9 a la secund\u00e0ria, al batxillerat i als cicles de formaci\u00f3 professional.<\/li><li>Podran fer activitats amb m\u00e9s de sis alumnes per aula nom\u00e9s els grups estables escolars o part d&#8217;aquests.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Oci educatiu<\/strong>:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Tant en espais interiors com a l&#8217;aire lliure i mantenint els grups m\u00e0xims de 6 persones.<\/li><li>Alumnes d&#8217;educaci\u00f3 infantil, prim\u00e0ria, i ara tamb\u00e9 els de secund\u00e0ria, batxillerat i cicles de formaci\u00f3 professional.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Equipaments c\u00edvics<\/strong>:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li>Podran fer activitats presencials a l&#8217;aire lliure els majors de 60 anys, siguin de caire f\u00edsic siguin d&#8217;entrenament de la mem\u00f2ria.<\/li><li>Els grups no podran superar les 6 persones.<\/li><li>Altres tipus d&#8217;activitats es podran fer exclusivament per mitjans telem\u00e0tic.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Activitats culturals<\/strong>: <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Les biblioteques, museus, arxius, sales d&#8217;exposicions, galeries d&#8217;art i centres de creaci\u00f3 i arts visuals poden organitzar activitats.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Tot de queda i confinament: <\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Finalment, el gruix de mesures ja vigents es mantenen, com el toc de queda i el confinament comarcal, que continuaran com fins ara.<\/p>\n\n\n\n<figure class=\"wp-block-image is-style-rounded\"><img decoding=\"async\" src=\"https:\/\/www.comunicado.es\/media\/backoffice\/files\/images\/pexels-photo-6205476.jpeg\" alt=\"Aquesta imatge t\u00e9 l'atribut alt buit; el seu nom \u00e9s pexels-photo-6205476.jpeg\"\/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Som assessors laborals i de la Seguretat Social. Consulteu-nos sense comprom\u00eds trucant al 972 208 258, o per correu electr\u00f2nic adre\u00e7at a info@rm-assessors.cat.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partir del 8 de mar\u00e7, els bars i restaurants podran obrir de dos quarts de vuit del mat\u00ed fins a les cinc de la tarda. Fora d&#8217;aquesta franja hor\u00e0ria, els clients no podran romandre a l&#8217;establiment. El Govern mantindr\u00e0 set dies m\u00e9s, fins al 15 de mar\u00e7, el gruix de les mesures actuals per [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,11],"tags":[1930,1931,1799],"class_list":["post-5629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-laboral","tag-covid-19-bars-restaurants","tag-mesures-8-marc","tag-noves-mesures-catalunya"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"A partir del 8 de mar\u00e7, els bars i restaurants podran obrir de dos quarts de vuit del mat\u00ed fins a les cinc de la tarda. Fora d&#8217;aquesta franja hor\u00e0ria, els clients no podran romandre a l&#8217;establiment. El Govern mantindr\u00e0 set dies m\u00e9s, fins al 15 de mar\u00e7, el gruix de les mesures actuals per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T09:06:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/07\/shutterstock_231985993.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7.\",\"datePublished\":\"2021-03-08T09:06:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/\"},\"wordCount\":473,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/shutterstock_231985993.jpg\",\"keywords\":[\"Covid-19 bars restaurants\",\"Mesures 8 mar\u00e7\",\"noves mesures Catalunya\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Laboral\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/\",\"name\":\"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/shutterstock_231985993.jpg\",\"datePublished\":\"2021-03-08T09:06:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/shutterstock_231985993.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/shutterstock_231985993.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/","og_locale":"es_ES","og_type":"article","og_title":"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7. | RM Assessors","og_description":"A partir del 8 de mar\u00e7, els bars i restaurants podran obrir de dos quarts de vuit del mat\u00ed fins a les cinc de la tarda. Fora d&#8217;aquesta franja hor\u00e0ria, els clients no podran romandre a l&#8217;establiment. El Govern mantindr\u00e0 set dies m\u00e9s, fins al 15 de mar\u00e7, el gruix de les mesures actuals per [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2021-03-08T09:06:13+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/07\/shutterstock_231985993.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7.","datePublished":"2021-03-08T09:06:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/"},"wordCount":473,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/07\/shutterstock_231985993.jpg","keywords":["Covid-19 bars restaurants","Mesures 8 mar\u00e7","noves mesures Catalunya"],"articleSection":["Butllet\u00ed mensual","Destacats","Laboral"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/","url":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/","name":"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/07\/shutterstock_231985993.jpg","datePublished":"2021-03-08T09:06:13+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/07\/shutterstock_231985993.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/07\/shutterstock_231985993.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/covid-19-bars-i-restaurants-poden-obrir-fins-a-les-5-de-la-tarda-a-partir-del-dilluns-8-de-marc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"COVID-19. Hosteleria amplia horaris el 8 de mar\u00e7."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/5629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=5629"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/5629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/4632"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=5629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=5629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=5629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}