{"id":5882,"date":"2021-05-19T18:56:44","date_gmt":"2021-05-19T16:56:44","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/"},"modified":"2021-05-19T18:56:44","modified_gmt":"2021-05-19T16:56:44","slug":"noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/","title":{"rendered":"Noves mesures a Catalunya a partir del 24 de maig de 2021"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">Els bars obriran a les sis del mat\u00ed des del dilluns 24 de maig i els comer\u00e7os ampliaran els seus aforaments.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">La Generalitat de Catalunya ha anunciat que es flexibilitzaran encara m\u00e9s algunes de les mesures de lluita contra la pand\u00e8mia de la COVID-19\u00a0<strong>des del pr\u00f2xim 24 de maig<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quins canvis es produiran?<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Restauraci\u00f3:&nbsp;<\/strong>hi haur\u00e0 una ampliaci\u00f3 de l&#8217;horari. Es podr\u00e0 obrir de 6.00 a 23.00 h.<\/li><li><strong>Cultura:&nbsp;<\/strong>s&#8217;ampliar\u00e0 l&#8217;aforament al 70%, amb un l\u00edmit de 1.000 persones en interiors o de 3.000 en exteriors.<\/li><li><strong>Comer\u00e7os:&nbsp;<\/strong>s&#8217;ampliar\u00e0 l&#8217;aforament al 50%.<\/li><li><strong>Universitats:&nbsp;<\/strong>s&#8217;ampliar\u00e0 l&#8217;aforament al 50%.<\/li><li><strong>Congressos i convencions:&nbsp;<\/strong>no necessitaran autoritzaci\u00f3 expressa del Procicat. L&#8217;aforament m\u00e0xim ser\u00e0 del 50%.<\/li><li><strong>Actes religiosos:&nbsp;<\/strong>es mantindr\u00e0 l&#8217;aforament del 50%, per\u00f2 s&#8217;ampliar\u00e0 el nombre d&#8217;assistents: 1.000 a l&#8217;interior i 3.000 a l&#8217;exterior.<\/li><li><strong>Esport:&nbsp;<\/strong>aforament del 50%. El nombre m\u00e0xim d&#8217;assistents ser\u00e0 de 1.000 a l&#8217;interior i 3.000 a l&#8217;exterior.<\/li><li><strong>Educaci\u00f3 en oci i formaci\u00f3 no reglada:&nbsp;<\/strong>es permetran grups de 10 persones.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg\"><img decoding=\"async\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg\" alt=\"\" class=\"wp-image-2194\"\/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\"><em>Som Gestors Administratius. Consulteu-nos sense comprom\u00eds<\/em><\/h3>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Els bars obriran a les sis del mat\u00ed des del dilluns 24 de maig i els comer\u00e7os ampliaran els seus aforaments.<\/p>\n","protected":false},"author":1,"featured_media":3321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,11],"tags":[1989,1799,1923],"class_list":["post-5882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-laboral","tag-mesures-24-maig","tag-noves-mesures-catalunya","tag-noves-mesures-covid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Noves mesures a Catalunya a partir del 24 de maig de 2021 | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Noves mesures a Catalunya a partir del 24 de maig de 2021 | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Els bars obriran a les sis del mat\u00ed des del dilluns 24 de maig i els comer\u00e7os ampliaran els seus aforaments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-19T16:56:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"583\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Noves mesures a Catalunya a partir del 24 de maig de 2021\",\"datePublished\":\"2021-05-19T16:56:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/\"},\"wordCount\":192,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_12.jpg\",\"keywords\":[\"mesures 24 maig\",\"noves mesures Catalunya\",\"Noves mesures Covid\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Laboral\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/\",\"name\":\"Noves mesures a Catalunya a partir del 24 de maig de 2021 | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_12.jpg\",\"datePublished\":\"2021-05-19T16:56:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_12.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_12.jpg\",\"width\":900,\"height\":583},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Noves mesures a Catalunya a partir del 24 de maig de 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Noves mesures a Catalunya a partir del 24 de maig de 2021 | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/","og_locale":"es_ES","og_type":"article","og_title":"Noves mesures a Catalunya a partir del 24 de maig de 2021 | RM Assessors","og_description":"Els bars obriran a les sis del mat\u00ed des del dilluns 24 de maig i els comer\u00e7os ampliaran els seus aforaments.","og_url":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2021-05-19T16:56:44+00:00","og_image":[{"width":900,"height":583,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Noves mesures a Catalunya a partir del 24 de maig de 2021","datePublished":"2021-05-19T16:56:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/"},"wordCount":192,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg","keywords":["mesures 24 maig","noves mesures Catalunya","Noves mesures Covid"],"articleSection":["Butllet\u00ed mensual","Destacats","Laboral"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/","url":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/","name":"Noves mesures a Catalunya a partir del 24 de maig de 2021 | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg","datePublished":"2021-05-19T16:56:44+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_12.jpg","width":900,"height":583},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/noves-mesures-a-catalunya-a-partir-del-24-de-maig-de-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Noves mesures a Catalunya a partir del 24 de maig de 2021"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/5882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=5882"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/5882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/3321"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=5882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=5882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=5882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}