{"id":6369,"date":"2022-01-28T08:10:30","date_gmt":"2022-01-28T06:10:30","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/final-de-les-restriccions-pel-covid-19\/"},"modified":"2022-01-28T08:10:30","modified_gmt":"2022-01-28T06:10:30","slug":"final-de-les-restriccions-pel-covid-19","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/","title":{"rendered":"Final de les restriccions pel Covid 19 ?"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\">A partir de les 0:00 hores del 28 de gener queden aixecades totes les mesures per combatre la pand\u00e8mia, sols resta tancat l&#8217;oci nocturn i es mant\u00e9 l&#8217;\u00fas obligatori de la mascareta.<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">El DOG del 27 de gener publica la <a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8593\/1888086.pdf\"><em>RESOLUCI\u00d3 SLT\/99\/2022, de 26 de gener<\/em><\/a> que acorda aixecar casi totes les mesures anti covid. Destaquem:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Entrada en vigor:<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A patir de les 0.00 h. d&#8217;avui, 28 de gener de 2022.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mesures que es mantenen de moment: <\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Tancament de l&#8217;oci nocturn (es preveu que es pugui obrir en poc temps).<\/li><li>Us obligatori de la mascareta (es una disposici\u00f3 estatal).<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Principals mesures que ja no estan en vigor:<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Limitaci\u00f3 de reunions a 10 persones.<\/li><li>Limitaci\u00f3 d&#8217;aforament en bars, restaurants i espectacles p\u00fablics.<\/li><li>Passaport covid per accedir a determinats establiments.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\" alt=\"\" class=\"wp-image-4185\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187-300x300.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<h5 class=\"wp-block-heading\">Som Gestors Administratius. Consulteu-nos sense comprom\u00eds<\/h5>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A partir de les 0:00 hores del 28 de gener queden aixecades totes les mesures per combatre la pand\u00e8mia, sols resta tancat l&#8217;oci nocturn i es mant\u00e9 l&#8217;\u00fas obligatori de la mascareta.<\/p>\n","protected":false},"author":1,"featured_media":3338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,15],"tags":[1923,2083],"class_list":["post-6369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-rm-assessors","tag-noves-mesures-covid","tag-restriccions-covid-19"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Final de les restriccions pel Covid 19 ? | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Final de les restriccions pel Covid 19 ? | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"A partir de les 0:00 hores del 28 de gener queden aixecades totes les mesures per combatre la pand\u00e8mia, sols resta tancat l&#039;oci nocturn i es mant\u00e9 l&#039;\u00fas obligatori de la mascareta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-28T06:10:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/10\/shutterstock_423223252.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"Final de les restriccions pel Covid 19 ?\",\"datePublished\":\"2022-01-28T06:10:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/\"},\"wordCount\":140,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/shutterstock_423223252.jpg\",\"keywords\":[\"Noves mesures Covid\",\"restriccions Covid 19\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"RM-Assessors\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/\",\"name\":\"Final de les restriccions pel Covid 19 ? | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/shutterstock_423223252.jpg\",\"datePublished\":\"2022-01-28T06:10:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/shutterstock_423223252.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/shutterstock_423223252.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/final-de-les-restriccions-pel-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Final de les restriccions pel Covid 19 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Final de les restriccions pel Covid 19 ? | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Final de les restriccions pel Covid 19 ? | RM Assessors","og_description":"A partir de les 0:00 hores del 28 de gener queden aixecades totes les mesures per combatre la pand\u00e8mia, sols resta tancat l'oci nocturn i es mant\u00e9 l'\u00fas obligatori de la mascareta.","og_url":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2022-01-28T06:10:30+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/10\/shutterstock_423223252.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"Final de les restriccions pel Covid 19 ?","datePublished":"2022-01-28T06:10:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/"},"wordCount":140,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/10\/shutterstock_423223252.jpg","keywords":["Noves mesures Covid","restriccions Covid 19"],"articleSection":["Butllet\u00ed mensual","Destacats","RM-Assessors"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/","url":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/","name":"Final de les restriccions pel Covid 19 ? | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/10\/shutterstock_423223252.jpg","datePublished":"2022-01-28T06:10:30+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/10\/shutterstock_423223252.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2018\/10\/shutterstock_423223252.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/final-de-les-restriccions-pel-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Final de les restriccions pel Covid 19 ?"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/6369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=6369"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/6369\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/3338"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=6369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=6369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=6369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}