{"id":6400,"date":"2022-02-15T12:02:38","date_gmt":"2022-02-15T10:02:38","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/"},"modified":"2022-02-15T12:02:38","modified_gmt":"2022-02-15T10:02:38","slug":"el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/","title":{"rendered":"El confinament del 2020 va tancar el teu negoci? L&#8217;asseguradora potser t&#8217;hauria d&#8217;indemnitzar."},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><strong>L\u2019Audi\u00e8ncia Provincial de Girona i alguns jutjats de primera inst\u00e0ncia s&#8217;han pronunciat recentment sobre la proced\u00e8ncia de la indemnitzaci\u00f3 per paralitzaci\u00f3 de l&#8217;activitat negocial per part de la legislaci\u00f3 estatal COVID-19, reconeixent el dret dels assegurats a demanar dita indemnitzaci\u00f3 a la seva companya asseguradora.<\/strong><strong><\/strong><\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Dues pioneres sent\u00e8ncies de l\u2019Audi\u00e8ncia Provincial de Girona de 3 de febrer i 16 de juny, emeses per la secci\u00f3 primera i segona respectivament, han marcat una direcci\u00f3 jurisprudencial que ha estat seguida per diversos jutjats de primera inst\u00e0ncia com els de Granada, Lorca, Pamplona&#8230; En ella, es determina que sempre que hi hagi alguna condici\u00f3 particular referent al dret d&#8217;indemnitzaci\u00f3 del negoci per paralitzaci\u00f3 de l\u2019activitat, p\u00e8rdua d\u2019explotaci\u00f3 amb indemnitzaci\u00f3 di\u00e0ria, p\u00e8rdua de beneficis, etc. la companyia asseguradora ha de procedir a la seva indemnitzaci\u00f3 encara que al mateix contracte d&#8217;asseguran\u00e7a ho prohibeixi expressament en una cl\u00e0usula general,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atenent que el per\u00edode de prescripci\u00f3 de l&#8217;acci\u00f3 \u00e9s de dos anys,<strong> aquest 14 de mar\u00e7 prescriu la responsabilitat de les asseguradores <\/strong>i no se&#8217;ls podr\u00e0 reclamar el que els pertoca als negocis.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg\" alt=\"\" class=\"wp-image-4185\" srcset=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187.jpg 600w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187-300x300.jpg 300w, https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1628196187-150x150.jpg 150w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Si vols que analitzem el teu cas, i valorem si pots ser un dels consumidors afectats, no dubtis a contactar amb nosaltres al 972208258 o juridic@rm-assessors.cat<\/em><\/strong><\/p>\n\n\n\n<div class=\"wp-block-contact-form-7-contact-form-selector\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Audi\u00e8ncia Provincial de Girona i alguns jutjats de primera inst\u00e0ncia s&#8217;han pronunciat recentment sobre la proced\u00e8ncia de la indemnitzaci\u00f3 per paralitzaci\u00f3 de l&#8217;activitat negocial per part de la legislaci\u00f3 estatal COVID-19, reconeixent el dret dels assegurats a demanar dita indemnitzaci\u00f3 a la seva companya asseguradora.<\/p>\n","protected":false},"author":1,"featured_media":4226,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,17],"tags":[2169,2170,2171],"class_list":["post-6400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-juridica","tag-indemnitzacio-assegurances-covid","tag-indemnitzacio-tancament-covid","tag-reclamar-asseguradores-covid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El confinament del 2020 va tancar el teu negoci? L&#039;asseguradora potser t&#039;hauria d&#039;indemnitzar. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El confinament del 2020 va tancar el teu negoci? L&#039;asseguradora potser t&#039;hauria d&#039;indemnitzar. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"L\u2019Audi\u00e8ncia Provincial de Girona i alguns jutjats de primera inst\u00e0ncia s&#039;han pronunciat recentment sobre la proced\u00e8ncia de la indemnitzaci\u00f3 per paralitzaci\u00f3 de l&#039;activitat negocial per part de la legislaci\u00f3 estatal COVID-19, reconeixent el dret dels assegurats a demanar dita indemnitzaci\u00f3 a la seva companya asseguradora.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-15T10:02:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1624415920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"El confinament del 2020 va tancar el teu negoci? L&#8217;asseguradora potser t&#8217;hauria d&#8217;indemnitzar.\",\"datePublished\":\"2022-02-15T10:02:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/\"},\"wordCount\":238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1624415920.jpg\",\"keywords\":[\"indemnitzaci\u00f3 assegurances Covid\",\"indemnitzaci\u00f3 tancament Covid\",\"reclamar asseguradores Covid\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Jur\u00eddica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/\",\"name\":\"El confinament del 2020 va tancar el teu negoci? L'asseguradora potser t'hauria d'indemnitzar. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1624415920.jpg\",\"datePublished\":\"2022-02-15T10:02:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1624415920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/shutterstock_1624415920.jpg\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El confinament del 2020 va tancar el teu negoci? L&#8217;asseguradora potser t&#8217;hauria d&#8217;indemnitzar.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El confinament del 2020 va tancar el teu negoci? L'asseguradora potser t'hauria d'indemnitzar. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/","og_locale":"es_ES","og_type":"article","og_title":"El confinament del 2020 va tancar el teu negoci? L'asseguradora potser t'hauria d'indemnitzar. | RM Assessors","og_description":"L\u2019Audi\u00e8ncia Provincial de Girona i alguns jutjats de primera inst\u00e0ncia s'han pronunciat recentment sobre la proced\u00e8ncia de la indemnitzaci\u00f3 per paralitzaci\u00f3 de l'activitat negocial per part de la legislaci\u00f3 estatal COVID-19, reconeixent el dret dels assegurats a demanar dita indemnitzaci\u00f3 a la seva companya asseguradora.","og_url":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2022-02-15T10:02:38+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1624415920.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"El confinament del 2020 va tancar el teu negoci? L&#8217;asseguradora potser t&#8217;hauria d&#8217;indemnitzar.","datePublished":"2022-02-15T10:02:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/"},"wordCount":238,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1624415920.jpg","keywords":["indemnitzaci\u00f3 assegurances Covid","indemnitzaci\u00f3 tancament Covid","reclamar asseguradores Covid"],"articleSection":["Butllet\u00ed mensual","Destacats","Jur\u00eddica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/","url":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/","name":"El confinament del 2020 va tancar el teu negoci? L'asseguradora potser t'hauria d'indemnitzar. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1624415920.jpg","datePublished":"2022-02-15T10:02:38+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1624415920.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2020\/03\/shutterstock_1624415920.jpg","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/el-confinament-del-2020-va-tancar-el-teu-negoci-lasseguradora-potser-thauria-dindemnitzar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El confinament del 2020 va tancar el teu negoci? L&#8217;asseguradora potser t&#8217;hauria d&#8217;indemnitzar."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/6400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=6400"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/6400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/4226"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=6400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=6400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=6400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}