{"id":7583,"date":"2018-03-26T10:49:57","date_gmt":"2018-03-26T08:49:57","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/"},"modified":"2018-03-26T10:49:57","modified_gmt":"2018-03-26T08:49:57","slug":"la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/","title":{"rendered":"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO)"},"content":{"rendered":"<p>Segons hem vingut informant, el proper dia 25 de maig del 2018 entrar\u00e0 en vigor el nou Reglament Europeu General de Protecci\u00f3 de Dades (RGPD), relatiu a la protecci\u00f3 de les persones f\u00edsiques pel que fa al tractament de dades personals i a la lliure circulaci\u00f3 d&#8217;aquestes dades.<\/p>\n<p>Una de les obligacions que est\u00e0 causant m\u00e9s pol\u00e8mica \u00e9s la figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO). <span style=\"color: #0000ff;\"><strong>Destaquem el seg\u00fcent:<\/strong> <\/span><\/p>\n<p><strong><span style=\"color: #ff0000;\">El DPO podr\u00e0 estar en plantilla o ser un consultor extern a l&#8217;organitzaci\u00f3 ?<\/span><\/strong> Les dues opcions seran possibles, per\u00f2 independentment de quina sigui l&#8217;opci\u00f3 escollida, aquesta persona haur\u00e0 d&#8217;actuar amb total independ\u00e8ncia en les seves funcions per tal de garantir que es compleixi la normativa.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Quines empreses o entitats hauran de tenir un DPO ? <\/span><\/strong>Actualment s&#8217;est\u00e0 elaborant una nova Llei Org\u00e0nica de Protecci\u00f3 de Dades (LOPD) que derogar\u00e0 l&#8217;actual i s&#8217;adaptar\u00e0 al nou Reglament Europeu. El projecte de la nova Llei Org\u00e0nica, en el seu article 34, enumera una s\u00e8rie d&#8217;entitats en les quals ser\u00e0 obligat\u00f2ria la designaci\u00f3 d&#8217;un DPO:<\/p>\n<ul>\n<li>Col\u00b7legis professionals<\/li>\n<li>Centres docents, que ofereixin ensenyaments reglats i les universitats p\u00fabliques i privades.<\/li>\n<li>Prestadors de serveis de comunicacions electr\u00f2niques, incloses les companyies telef\u00f2niques i els prove\u00efdors d&#8217;acc\u00e9s a internet, sempre que tractin perfils a gran escala.<\/li>\n<li>Prestadors de serveis de la societat de la informaci\u00f3, quan elaborin a gran escala perfils dels usuaris del servei.<\/li>\n<li>Entitats de cr\u00e8dit (bancs, les caixes d&#8217;estalvis, les cooperatives de cr\u00e8dit i l&#8217;Institut de Cr\u00e8dit Oficial).<\/li>\n<li>Empreses de foment del finan\u00e7ament empresarial.<\/li>\n<li>Entitats asseguradores.<\/li>\n<li>Empreses de serveis d&#8217;inversi\u00f3 que ofereixin serveis d&#8217;inversi\u00f3 bors\u00e0ries i de fons d&#8217;estalvi.<\/li>\n<li>Distribu\u00efdores i comercialitzadores d&#8217;electricitat.<\/li>\n<li>Organitzacions que avaluen la solv\u00e8ncia patrimonial i cr\u00e8dit.<\/li>\n<li>S&#8217;inclouen els responsables dels fitxers regulats per la Llei de prevenci\u00f3 del blanqueig de capitals i del finan\u00e7ament del terrorisme.<\/li>\n<li>Empreses de publicitat i prospecci\u00f3 comercial, incloses empreses que elaborin perfils del consumidor.<\/li>\n<li>Centres sanitaris.<\/li>\n<li>Emissors d&#8217;informes comercials.<\/li>\n<li>Operadors de joc electr\u00f2nic.<\/li>\n<li>Empreses de seguretat privada, activitats regulades pel T\u00edtol II de la Llei 5\/2014, de 4 d&#8217;abril, de Seguretat Privada, i tamb\u00e9 els despatxos de detectius privats.<\/li>\n<\/ul>\n<p>Les empreses podran decidir, encara que no sigui obligatori, comptar amb\u00a0 DPO\u00a0 intern o extern<\/p>\n<p>Un grup empresarial podr\u00e0 nomenar un \u00fanic delegat de protecci\u00f3 de dades.<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Quins requisits haur\u00e0 de reunir un DPO ?<\/strong><\/span><\/p>\n<ul>\n<li>El DPO haur\u00e0 de comptar amb coneixements t\u00e8cnics i jur\u00eddics, i \u00f2bviament en protecci\u00f3 de dades i actuar\u00e0 de forma independent.<\/li>\n<li>El DPO podr\u00e0 formar part de la plantilla del responsable o exercir les seves funcions en el marc d&#8217;un contracte de serveis.<\/li>\n<\/ul>\n<p><span style=\"color: #ff0000;\"><strong>Quines seran les principals funcions del DPO ?<\/strong><\/span><\/p>\n<ul>\n<li>Informar i assessorar al responsable i als empleats que s&#8217;ocupin del tractament de les obligacions que els incumbeixen.<\/li>\n<li>Supervisar el compliment del que es disposa en el RGPD i altres disposicions de protecci\u00f3 de dades.<\/li>\n<li>Oferir l&#8217;assessorament que se li sol\u00b7liciti sobre l&#8217;avaluaci\u00f3 d&#8217;impacte relativa a la protecci\u00f3 de dades.<\/li>\n<li>Cooperar i actuar com a punt de contacte amb l&#8217;autoritat de control.<\/li>\n<\/ul>\n<p><strong><span style=\"color: #ff0000;\">Qui es podr\u00e0 certificat com a DPO ? <\/span><\/strong>L&#8217;Ag\u00e8ncia Espanyola de Protecci\u00f3 de Dades (AEPD), en col\u00b7laboraci\u00f3 amb l&#8217;Entitat Nacional d&#8217;Acreditaci\u00f3 (ENAC), ha presentat un esquema de certificaci\u00f3 per a l&#8217;exercici professional de delegat de protecci\u00f3 de dades.<\/p>\n<p>No obstant aix\u00f2, cal destacar que aquesta certificaci\u00f3 no ser\u00e0 obligat\u00f2ria, si b\u00e9 aquest sistema de certificaci\u00f3 ofereix una seguretat i fiabilitat per a les empreses quant al fet que tots aquells que superin aquest esquema de certificaci\u00f3 comptaran amb els coneixements i aptituds necess\u00e0ries per poder exercir la seva labor com a DPO.<\/p>\n<p>No obstant aix\u00f2, a causa que es tracta d&#8217;un esquema de recent creaci\u00f3 el dia d&#8217;avui encara no hi ha entitats acreditades per a aquesta activitat de certificaci\u00f3, \u00fanicament, una primera autoritzaci\u00f3, que de moment \u00e9s provisional, emesa per l&#8217;Ag\u00e8ncia Espanyola de Protecci\u00f3 de Dades. <a href=\"http:\/\/www.agpd.es\/portalwebAGPD\/temas\/certificacion\/index-ides-idphp.php\"><span style=\"color: #ff0000;\"><em>Per a m\u00e9s informaci\u00f3 podeu fer clic aqu\u00ed<\/em><\/span><\/a>.<\/p>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2188\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/a><\/p>\n<p><span style=\"color: #ff0000;\"><em><strong>Gestionem la protecci\u00f3 de dades de la vostra empresa. Consulteu-nos sense comprom\u00eds trucant al 972 426 082, o per correu electr\u00f2nic adre\u00e7at a la nostra assessora, mariaromaguera@rm-assessors.cat.<\/strong> <\/em><\/span><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segons hem vingut informant, el proper dia 25 de maig del 2018 entrar\u00e0 en vigor el nou Reglament Europeu General de Protecci\u00f3 de Dades (RGPD), relatiu a la protecci\u00f3 de les persones f\u00edsiques pel que fa al tractament de dades personals i a la lliure circulaci\u00f3 d&#8217;aquestes dades. Una de les obligacions que est\u00e0 causant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,16],"tags":[932,933,546],"class_list":["post-7583","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-fiscal-i-comptable","tag-delegat-proteccio-dades","tag-nova-proteccio-dades","tag-proteccio-dades-empreses"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO) | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO) | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Segons hem vingut informant, el proper dia 25 de maig del 2018 entrar\u00e0 en vigor el nou Reglament Europeu General de Protecci\u00f3 de Dades (RGPD), relatiu a la protecci\u00f3 de les persones f\u00edsiques pel que fa al tractament de dades personals i a la lliure circulaci\u00f3 d&#8217;aquestes dades. Una de les obligacions que est\u00e0 causant [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-26T08:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral4_15956001-Copia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"658\" \/>\n\t<meta property=\"og:image:height\" content=\"325\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO)\",\"datePublished\":\"2018-03-26T08:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/\"},\"wordCount\":748,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral4_15956001-Copia.jpg\",\"keywords\":[\"delegat protecci\u00f3 dades\",\"nova protecci\u00f3 dades\",\"protecci\u00f3 dades empreses\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Fiscal i comptable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/\",\"name\":\"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO) | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral4_15956001-Copia.jpg\",\"datePublished\":\"2018-03-26T08:49:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral4_15956001-Copia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/laboral4_15956001-Copia.jpg\",\"width\":658,\"height\":325},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO) | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/","og_locale":"es_ES","og_type":"article","og_title":"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO) | RM Assessors","og_description":"Segons hem vingut informant, el proper dia 25 de maig del 2018 entrar\u00e0 en vigor el nou Reglament Europeu General de Protecci\u00f3 de Dades (RGPD), relatiu a la protecci\u00f3 de les persones f\u00edsiques pel que fa al tractament de dades personals i a la lliure circulaci\u00f3 d&#8217;aquestes dades. Una de les obligacions que est\u00e0 causant [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2018-03-26T08:49:57+00:00","og_image":[{"width":658,"height":325,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral4_15956001-Copia.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO)","datePublished":"2018-03-26T08:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/"},"wordCount":748,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral4_15956001-Copia.jpg","keywords":["delegat protecci\u00f3 dades","nova protecci\u00f3 dades","protecci\u00f3 dades empreses"],"articleSection":["Butllet\u00ed mensual","Destacats","Fiscal i comptable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/","url":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/","name":"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO) | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral4_15956001-Copia.jpg","datePublished":"2018-03-26T08:49:57+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral4_15956001-Copia.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2015\/02\/laboral4_15956001-Copia.jpg","width":658,"height":325},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/la-nova-figura-del-delegat-de-proteccio-de-dades-o-data-protection-officer-dpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La nova figura del delegat de protecci\u00f3 de dades o Data Protection Officer (DPO)"}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/7583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=7583"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/7583\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/667"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=7583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=7583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=7583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}