{"id":7595,"date":"2018-05-07T11:54:23","date_gmt":"2018-05-07T09:54:23","guid":{"rendered":"https:\/\/www.rm-assessors.cat\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/"},"modified":"2018-05-07T11:54:23","modified_gmt":"2018-05-07T09:54:23","slug":"lagencia-tributaria-esta-comprovant-les-declaracions-diva","status":"publish","type":"post","link":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/","title":{"rendered":"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA."},"content":{"rendered":"<p>Hem rebut informaci\u00f3 que l&#8217;Ag\u00e8ncia Tribut\u00e0ria ha iniciat una campanya per comprovar la informaci\u00f3 facilitada pels bancs (d&#8217;entrades i sortides en els comptes) amb els imports declarats en l&#8217;IVA, i si detecta discrep\u00e0ncies considerables, podr\u00e0 iniciar procediments de comprovaci\u00f3 o fins i tot, visites sorpresa a aquelles empreses amb incoher\u00e8ncies.<\/p>\n<p>Aquesta actuaci\u00f3 estaria en l\u00ednia amb les directrius generals del Pla anual de control tributari i duaner de 2018.<\/p>\n<p>En el marc d&#8217;aquesta campanya, el Departament de Gesti\u00f3 Tribut\u00e0ria de l\u2019AEAT ha enviat a determinats contribuents una comunicaci\u00f3 amb l&#8217;objecte d\u2019informar-los que l&#8217;Ag\u00e8ncia Tribut\u00e0ria disposa des de 2016 de la informaci\u00f3 de les entrades i sortides totals de tots els comptes bancaris dels contribuents, tant de persones f\u00edsiques com d&#8217;entitats.<\/p>\n<p>En aquestes comunicacions, que no inicien cap procediment tributari i en les quals no se sol\u00b7licita cap documentaci\u00f3, s&#8217;informa de la possible incoher\u00e8ncia entre les quanties declarades en les autoliquidacions de l&#8217;IVA amb la suma dels c\u00e0rrecs i dels abonaments en els comptes bancaris.<\/p>\n<p>Tamb\u00e9 s\u2019avisa que l\u2019Ag\u00e8ncia Tribut\u00e0ria pot creuar aquesta informaci\u00f3 amb les declaracions de l&#8217;IVA de l&#8217;exercici 2017 i de les conseq\u00fc\u00e8ncies econ\u00f2miques que aix\u00f2 podria comportar i aprofita per comunicar els imports acumulats el 2017 de les entrades en els comptes bancaris dels quals una persona o entitat \u00e9s titular o autoritzat.<\/p>\n<p>En la carta d&#8217;aquest any, igual que en la de l&#8217;any passat, s&#8217;adverteix que \u00e9s una mera comunicaci\u00f3 de dades, per la qual cosa no s&#8217;ha d&#8217;enviar documentaci\u00f3 ni justificar l&#8217;import dels abonaments o c\u00e0rrecs en els comptes bancaris dels quals ha estat informat, i tan sols \u00e9s informaci\u00f3 rebuda per l\u2019AEAT que es posa a la seva disposici\u00f3.<\/p>\n<p>Sembla que amb aquesta carta, Hisenda tracta de dissuadir als contribuents que evitin cometre irregularitats en les seves declaracions d\u2019IVA, amb l&#8217;advertiment de la facilitat de detecci\u00f3 de fraus, en tenir acc\u00e9s a les dades dels seus comptes bancaris.<\/p>\n<p>Pot ser que existeixin difer\u00e8ncies entre els moviments bancaris i les dades declarades en l&#8217;IVA, que poden cridar l&#8217;atenci\u00f3 d&#8217;Hisenda, i que no impliquen necess\u00e0riament l&#8217;exist\u00e8ncia de vendes no declarades. En aquest cas, convindria tenir preparada tota la documentaci\u00f3 que justifiqui l&#8217;exist\u00e8ncia de les discrep\u00e0ncies, per tenir-ho tot preparat en el cas de ser objecte d&#8217;actuacions de comprovaci\u00f3.<\/p>\n<p><a href=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-2188\" src=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg\" alt=\"\" width=\"900\" height=\"600\" \/><\/a><\/p>\n<p><span style=\"color: #0000ff;\"><em><strong>Som assessors fiscals. Consulteu-nos sense comprom\u00eds trucant al 972 426 082, o per correu electr\u00f2nic adre\u00e7at a algun dels nostres assessors fiscals: <a href=\"mailto:antoninavarro@rm-assessors.cat\">antoninavarro@rm-assessors.cat<\/a>, <a href=\"mailto:mariaromaguera@rm-assessors.cat\">mariaromaguera@rm-assessors.cat<\/a>, o, <a href=\"mailto:carlesvilanova@rm-assessors.cat\">carlesvilanova@rm-assessors.cat<\/a>.<\/strong><\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hem rebut informaci\u00f3 que l&#8217;Ag\u00e8ncia Tribut\u00e0ria ha iniciat una campanya per comprovar la informaci\u00f3 facilitada pels bancs (d&#8217;entrades i sortides en els comptes) amb els imports declarats en l&#8217;IVA, i si detecta discrep\u00e0ncies considerables, podr\u00e0 iniciar procediments de comprovaci\u00f3 o fins i tot, visites sorpresa a aquelles empreses amb incoher\u00e8ncies. Aquesta actuaci\u00f3 estaria en l\u00ednia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3315,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21,41,16],"tags":[971,972,973],"class_list":["post-7595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-butlleti-mensual","category-destacats","category-fiscal-i-comptable","tag-agencia-tributaria-iva","tag-avisos-control-iva","tag-comprovacions-inspeccio-iva"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA. | RM Assessors<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA. | RM Assessors\" \/>\n<meta property=\"og:description\" content=\"Hem rebut informaci\u00f3 que l&#8217;Ag\u00e8ncia Tribut\u00e0ria ha iniciat una campanya per comprovar la informaci\u00f3 facilitada pels bancs (d&#8217;entrades i sortides en els comptes) amb els imports declarats en l&#8217;IVA, i si detecta discrep\u00e0ncies considerables, podr\u00e0 iniciar procediments de comprovaci\u00f3 o fins i tot, visites sorpresa a aquelles empreses amb incoher\u00e8ncies. Aquesta actuaci\u00f3 estaria en l\u00ednia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/\" \/>\n<meta property=\"og:site_name\" content=\"RM Assessors\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rmassessors\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-07T09:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"neorg_US\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:site\" content=\"@RMAssessors\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"neorg_US\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/\"},\"author\":{\"name\":\"neorg_US\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\"},\"headline\":\"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA.\",\"datePublished\":\"2018-05-07T09:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/\"},\"wordCount\":465,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_6.jpg\",\"keywords\":[\"Ag\u00e8ncia Tribut\u00e0ria IVA\",\"avisos control IVA\",\"comprovacions inspecci\u00f3 IVA\"],\"articleSection\":[\"Butllet\u00ed mensual\",\"Destacats\",\"Fiscal i comptable\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/\",\"name\":\"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA. | RM Assessors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_6.jpg\",\"datePublished\":\"2018-05-07T09:54:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_6.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/RM_Assessors_Foto_6.jpg\",\"width\":900,\"height\":600,\"caption\":\"Woman hand Using modern laptop to view market indicator of investment graph and financial data, marketing analysis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"name\":\"RM Assessors\",\"description\":\"Assessoria i gestoria a Girona, Figueres i Breda.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\"},\"alternateName\":\"RM Assessors\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#organization\",\"name\":\"RM Assessors\",\"alternateName\":\"RM Assessors\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"contentUrl\":\"https:\\\/\\\/www.rm-assessors.cat\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/RM-Serveis_Assessors.svg\",\"width\":200,\"height\":200,\"caption\":\"RM Assessors\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rmassessors\",\"https:\\\/\\\/x.com\\\/RMAssessors\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rm-assessors\\\/\",\"https:\\\/\\\/www.instagram.com\\\/rm_assessors\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rm-assessors.cat\\\/es\\\/#\\\/schema\\\/person\\\/6319b8c64073cb2218768aa069a0e944\",\"name\":\"neorg_US\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g\",\"caption\":\"neorg_US\"},\"sameAs\":[\"https:\\\/\\\/www.rm-assessors.cat\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA. | RM Assessors","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/","og_locale":"es_ES","og_type":"article","og_title":"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA. | RM Assessors","og_description":"Hem rebut informaci\u00f3 que l&#8217;Ag\u00e8ncia Tribut\u00e0ria ha iniciat una campanya per comprovar la informaci\u00f3 facilitada pels bancs (d&#8217;entrades i sortides en els comptes) amb els imports declarats en l&#8217;IVA, i si detecta discrep\u00e0ncies considerables, podr\u00e0 iniciar procediments de comprovaci\u00f3 o fins i tot, visites sorpresa a aquelles empreses amb incoher\u00e8ncies. Aquesta actuaci\u00f3 estaria en l\u00ednia [&hellip;]","og_url":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/","og_site_name":"RM Assessors","article_publisher":"https:\/\/www.facebook.com\/rmassessors","article_published_time":"2018-05-07T09:54:23+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg","type":"image\/jpeg"}],"author":"neorg_US","twitter_card":"summary_large_image","twitter_creator":"@RMAssessors","twitter_site":"@RMAssessors","twitter_misc":{"Escrito por":"neorg_US","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#article","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/"},"author":{"name":"neorg_US","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944"},"headline":"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA.","datePublished":"2018-05-07T09:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/"},"wordCount":465,"commentCount":0,"publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg","keywords":["Ag\u00e8ncia Tribut\u00e0ria IVA","avisos control IVA","comprovacions inspecci\u00f3 IVA"],"articleSection":["Butllet\u00ed mensual","Destacats","Fiscal i comptable"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/","url":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/","name":"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA. | RM Assessors","isPartOf":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#primaryimage"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg","datePublished":"2018-05-07T09:54:23+00:00","breadcrumb":{"@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#primaryimage","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2017\/06\/RM_Assessors_Foto_6.jpg","width":900,"height":600,"caption":"Woman hand Using modern laptop to view market indicator of investment graph and financial data, marketing analysis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rm-assessors.cat\/es\/lagencia-tributaria-esta-comprovant-les-declaracions-diva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.rm-assessors.cat\/es\/"},{"@type":"ListItem","position":2,"name":"L\u2019Ag\u00e8ncia Tribut\u00e0ria est\u00e0 comprovant les declaracions d\u2019IVA."}]},{"@type":"WebSite","@id":"https:\/\/www.rm-assessors.cat\/es\/#website","url":"https:\/\/www.rm-assessors.cat\/es\/","name":"RM Assessors","description":"Assessoria i gestoria a Girona, Figueres i Breda.","publisher":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#organization"},"alternateName":"RM Assessors","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rm-assessors.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.rm-assessors.cat\/es\/#organization","name":"RM Assessors","alternateName":"RM Assessors","url":"https:\/\/www.rm-assessors.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","contentUrl":"https:\/\/www.rm-assessors.cat\/wp-content\/uploads\/2023\/09\/RM-Serveis_Assessors.svg","width":200,"height":200,"caption":"RM Assessors"},"image":{"@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rmassessors","https:\/\/x.com\/RMAssessors","https:\/\/www.linkedin.com\/company\/rm-assessors\/","https:\/\/www.instagram.com\/rm_assessors\/"]},{"@type":"Person","@id":"https:\/\/www.rm-assessors.cat\/es\/#\/schema\/person\/6319b8c64073cb2218768aa069a0e944","name":"neorg_US","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b63926e9b9d0dcf698d6148e42ad55d32fd25573ca6e03571bddf984706f7428?s=96&d=mm&r=g","caption":"neorg_US"},"sameAs":["https:\/\/www.rm-assessors.cat"]}]}},"_links":{"self":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/7595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/comments?post=7595"}],"version-history":[{"count":0,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/posts\/7595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media\/3315"}],"wp:attachment":[{"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/media?parent=7595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/categories?post=7595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rm-assessors.cat\/es\/wp-json\/wp\/v2\/tags?post=7595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}